{"id":248,"date":"2024-04-05T23:36:00","date_gmt":"2024-04-05T21:36:00","guid":{"rendered":"https:\/\/www.hirondelle.org\/?page_id=248"},"modified":"2026-04-30T09:49:34","modified_gmt":"2026-04-30T07:49:34","slug":"notre-equipe","status":"publish","type":"page","link":"https:\/\/www.hirondelle.org\/fr\/qui-sommes-nous\/notre-equipe","title":{"rendered":"Notre \u00e9quipe"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1090\" src=\"https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/10\/FondationHirondelle-1bis-scaled.jpg\" alt=\"\" class=\"wp-image-21073\" srcset=\"https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/10\/FondationHirondelle-1bis-scaled.jpg 2560w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/10\/FondationHirondelle-1bis-300x128.jpg 300w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/10\/FondationHirondelle-1bis-1024x436.jpg 1024w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/10\/FondationHirondelle-1bis-768x327.jpg 768w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/10\/FondationHirondelle-1bis-1536x654.jpg 1536w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/10\/FondationHirondelle-1bis-2048x872.jpg 2048w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/10\/FondationHirondelle-1bis-1000x426.jpg 1000w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n<script>\r\n\t\tvar team_configuration = {\"direction\":{\"title\":\"Direction\",\"members\":[{\"name\":\"Caroline Vuillemin\",\"title\":\"Directrice g\\u00e9n\\u00e9rale\",\"text\":\"Caroline Vuillemin est Directrice g\\u00e9n\\u00e9rale de la Fondation Hirondelle depuis le 1er janvier 2017. Sa carri\\u00e8re refl\\u00e8te un engagement dans le d\\u00e9veloppement international, en particulier avec l\\u2019Afrique. Elle a rejoint la Fondation Hirondelle en d\\u00e9cembre 2003. D\\u2019abord en charge du projet Radio Okapi (la radio des Nations Unies en RDC cr\\u00e9\\u00e9e en partenariat avec la Fondation Hirondelle), elle est devenue Directrice des op\\u00e9rations en 2008. Avant la Fondation Hirondelle, elle a travaill\\u00e9 pour la Fondation internationale pour les syst\\u00e8mes \\u00e9lectoraux (IFES) o\\u00f9 elle a particip\\u00e9 \\u00e0 de nombreuses missions d\\u2019observation \\u00e9lectorale en RDC, au Rwanda, au Burundi, en Afrique du Sud, au Nig\\u00e9ria et au Congo-Brazzaville. Caroline Vuillemin est titulaire d\\u2019une Licence de l\\u2019Institut d\\u2019\\u00e9tudes politiques de Lyon, compl\\u00e9t\\u00e9e par un dipl\\u00f4me en Relations internationales de l\\u2019Universit\\u00e9 de Georgetown \\u00e0 Washington, DC. Elle membre des Comit\\u00e9s du Global Forum for Media Development (GFMD), de la F\\u00e9d\\u00e9vaco (F\\u00e9d\\u00e9ration vaudoise de coop\\u00e9ration) et du r\\u00e9seau H2H (Humanitarian to Humanitarian).\"},{\"name\":\"Nicolas Boissez\",\"title\":\"Directeur des op\\u00e9rations\",\"text\":\"Nicolas Boissez est Directeur des op\\u00e9rations de la Fondation Hirondelle. Il dirige l\\u2019\\u00e9quipe des op\\u00e9rations et assure la responsabilit\\u00e9 globale de la pertinence et de l\\u2019efficacit\\u00e9 des projets et activit\\u00e9s de la Fondation.  Membre du comit\\u00e9 de Direction, il participe activement \\u00e0 la conduite g\\u00e9n\\u00e9rale de l\\u2019organisation et \\u00e0 l\\u2019atteinte de ses objectifs. Nicolas a rejoint la Fondation Hirondelle en 2008. Il a d\\u2019abord travaill\\u00e9 en tant que charg\\u00e9 de projet, puis charg\\u00e9 de programme. Il a notamment supervis\\u00e9 les projets Radio Okapi (RDC), Studio Mozaik (C\\u00f4te d\\u2019Ivoire) et Studio Tamani (Mali). Il a ensuite \\u00e9t\\u00e9 nomm\\u00e9 D\\u00e9l\\u00e9gu\\u00e9 \\u00e0 la communication et aux relations ext\\u00e9rieures de la Fondation, responsabilit\\u00e9 qu\\u2019il a assur\\u00e9e pendant 6 ans, jusque fin 2022. Avant de rejoindre la Fondation Hirondelle, Nicolas avait travaill\\u00e9 pour le Minist\\u00e8re fran\\u00e7ais des affaires \\u00e9trang\\u00e8res, \\u00e0 Kinshasa (RDC) comme Attach\\u00e9 audiovisuel r\\u00e9gional pour l\\u2019Afrique centrale, et \\u00e0 Hanoi (Vietnam) comme Attach\\u00e9 audiovisuel, en charge de la coop\\u00e9ration fran\\u00e7aise avec les m\\u00e9dias et producteurs audiovisuels de ces pays. Il a commenc\\u00e9 sa carri\\u00e8re comme journaliste \\u00e0 Nantes (France) pour le quotidien Ouest-France. Nicolas Boissez est titulaire d\\u2019une Licence en Information & Communication.\"},{\"name\":\"Christyl Vasserot\",\"title\":\"Directrice des supports et d\\u00e9veloppement institutionnel\",\"text\":\"Christyl a rejoint la fondation en Septembre 2025, en tant que Directrice du Support et des Services, un poste qui englobe la direction des p\\u00f4les suivants : finances, administration, RH , technique , recherche de fonds priv\\u00e9s, sant\\u00e9 et s\\u00e9curit\\u00e9 , que ce soit pour le terrain et pour le si\\u00e8ge . Elle est membre du conseil de direction. Au b\\u00e9n\\u00e9fice d\\u2019une longue exp\\u00e9rience en gestion d\\u2019\\u00e9quipes multidisciplinaires et de projets complexes, elle a d\\u00e9but\\u00e9 sa carri\\u00e8re en tant que gestionnaire de fortune dans diff\\u00e9rentes banques priv\\u00e9es \\u00e0 Gen\\u00e8ve. Elle a ensuite pass\\u00e9 pr\\u00e8s de 10 ans au Comit\\u00e9 International de la Croix Rouge , en Afrique et au Moyen Orient, principalement dans le domaine de la protection des personnes affect\\u00e9es par un conflit. De retour en Suisse elle a occup\\u00e9 depuis 2011 diff\\u00e9rents postes de cadre au sein de l\\u2019administration publique, \\u00e0 Gen\\u00e8ve et dans le Canton de Vaud , dans le domaine du social et de la d\\u00e9tention. Christyl est titulaire d\\u2019un Bachelor of Science in Business Administration de l\\u2019Universit\\u00e9 de Hartford aux USA, d\\u2019un DAS en gestion des Institutions Sociales de l\\u2019Universit\\u00e9 de Gen\\u00e8ve, et se forme de mani\\u00e8re continue aux questions de management et de gouvernance.\"}]},\"editorial\":{\"title\":\"\\u00c9ditorial \\\/ Communication \\\/ Recherche\",\"members\":[{\"name\":\"Jacqueline Dalton\",\"title\":\"Responsable \\u00e9ditoriale\",\"text\":\"Jacqueline Dalton encadre les activit\\u00e9s \\u00e9ditoriales de la Fondation Hirondelle. Elle intervient \\u00e0 travers les programmes et les r\\u00e9gions pour d\\u00e9finir la strat\\u00e9gie \\u00e9ditoriale et veiller \\u00e0 ce que le journalisme produit par l\\u2019organisation soit cr\\u00e9dible, utile et redevable envers ses publics. Elle collabore avec les \\u00e9quipes et partenaires locales afin de renforcer les pratiques professionnelles et soutenir un journalisme de qualit\\u00e9. Avant de rejoindre la Fondation Hirondelle en 2020, Jacqueline a occup\\u00e9 des postes de responsabilit\\u00e9 dans les domaines \\u00e9ditoriaux et du d\\u00e9veloppement des m\\u00e9dias \\u00e0 BBC Global News et \\u00e0 BBC Media Action, et a \\u00e9galement travaill\\u00e9 dans le secteur humanitaire. Son parcours couvre une grande diversit\\u00e9 de situations de crise \\u2014 conflits, al\\u00e9as naturels et urgences de sant\\u00e9 publique \\u2014 avec une attention particuli\\u00e8re port\\u00e9e \\u00e0 l\\u2019acc\\u00e8s des populations concern\\u00e9es \\u00e0 une information fiable et pratique, essentielle pour faire face et s\\u2019adapter. Jacqueline est titulaire d\\u2019un master en journalisme audiovisuel.\"},{\"name\":\"Julie Crenn\",\"title\":\"Sp\\u00e9cialiste Communication\",\"text\":\"Julie Crenn est Sp\\u00e9cialiste Communication \\u00e0 la Fondation Hirondelle. Elle assure la communication externe de la Fondation qu\\u2019elle a rejoint en septembre 2024. Julie Crenn a plus de 10 ans d\\u2019exp\\u00e9rience dans le domaine des m\\u00e9dias en tant que journaliste radio et de presse \\u00e9crite. Elle a \\u00e9galement travaill\\u00e9 comme Charg\\u00e9e de communication au Mali pour UNICEF puis comme Responsable communication \\u00e0 Mayotte pour un \\u00e9tablissement d\\u2019Etat, l\\u2019EPFAM. Elle est titulaire d\\u2019un DUT en Information-Communication et d\\u2019une licence en journalisme radio de l\\u2019IUT de Lannion (Universit\\u00e9 de Rennes) en 2010.\"},{\"name\":\"Sacha Meuter\",\"title\":\"Responsable de la recherche et des politiques\",\"text\":\"Sacha Meuter est Responsable de la recherche et des politiques \\u00e0 la Fondation Hirondelle. Il travaille dans les secteurs de la recherche et de l\\u2019appui aux m\\u00e9dias dans des contextes fragiles depuis pr\\u00e8s de 20 ans. \\u00c0 la Fondation Hirondelle, il est en charge du d\\u00e9veloppement des partenariats avec des acteurs acad\\u00e9miques, des groupes de r\\u00e9flexion et des policy makers. Son travail a notamment pour but de concevoir et de mettre en \\u0153uvre des \\u00e9tudes visant \\u00e0 comprendre la situation et l'impact des m\\u00e9dias ; d\\u2019\\u00e9laborer des outils d\\u2019analyse des flux d\\u2019information en ligne et hors ligne et d\\u2019am\\u00e9liorer les politiques globales visant \\u00e0 promouvoir l\\u2019int\\u00e9grit\\u00e9 de l\\u2019information. Il partage r\\u00e9guli\\u00e8rement son exp\\u00e9rience \\u00e0 travers des formations et dispositifs d\\u2019\\u00e9ducation aux m\\u00e9dias et \\u00e0 l\\u2019information. Son travail implique des missions fr\\u00e9quentes sur le terrain et la participation \\u00e0 des conf\\u00e9rences internationales. Sacha Meuter est \\u00e9galement membre du comit\\u00e9 de The New Humanitarian. Pr\\u00e9c\\u00e9demment, il a notamment travaill\\u00e9 pour la chaire de droit constitutionnel et \\u00e0 l\\u2019Institut interdisciplinaire d'\\u00e9thique et des droits humains de l\\u2019Universit\\u00e9 de Fribourg. Il a particip\\u00e9 \\u00e0 la d\\u00e9l\\u00e9gation suisse durant la cr\\u00e9ation du Conseil des droits de l\\u2019homme des Nations Unies. Il a men\\u00e9 des recherches en droit international et en sociologie du droit aux universit\\u00e9s de Glasgow et d\\u2019Oxford. Sacha Meuter est titulaire d\\u2019un Master en droit de l\\u2019Universit\\u00e9 de Fribourg. EN:Sacha Meuter is Head of Research and Policy at Fondation Hirondelle.\"}]},\"operations\":{\"title\":\"Op\\u00e9rations (*)\",\"members\":[{\"name\":\"Ouboul\\u00e9 Abalo\",\"title\":\"Repr\\u00e9sentant de la Fondation Hirondelle en R\\u00e9publique centrafricaine\",\"text\":\"Ouboul\\u00e8 Abalo est Repr\\u00e9sentant de la Fondation Hirondelle en Centrafrique depuis Septembre 2021. Il est juriste et dipl\\u00f4m\\u00e9 de l\\u2019Ecole Nationale d\\u2019Administration du B\\u00e9nin. Il s\\u2019est sp\\u00e9cialis\\u00e9 sur les questions de protection et des droits humains et cumule plus de 20 ans d\\u2019exp\\u00e9rience terrain dans les contextes humanitaires et de d\\u00e9veloppement. Il a assur\\u00e9 la coordination de nombreux programmes (gouvernance, sant\\u00e9, justice, acc\\u00e8s aux droits, protection de l\\u2019enfance, violences sexuelles et bas\\u00e9es sur le genre, entre autres) en Afrique de l\\u2019Ouest et du Centre. Avant de rejoindre la Fondation Hirondelle, Ouboul\\u00e8 Abalo a occup\\u00e9 des fonctions de d\\u00e9l\\u00e9gu\\u00e9 national, coordinateur terrain, chef d\\u2019antenne, chef de mission, directeur pays au sein des organisations telles que Plan\\u00e8te Urgence, RCN Justice & D\\u00e9mocratie, Action Contre la Faim, M\\u00e9decins du Monde Belgique, Avocats Sans Fronti\\u00e8res, etc. Cet itin\\u00e9raire professionnel lui a permis d\\u2019acqu\\u00e9rir des comp\\u00e9tences techniques et manag\\u00e9riales vari\\u00e9es qui se sont renforc\\u00e9es au fil des ann\\u00e9es.\"},{\"name\":\"Sabra Ayres\",\"title\":\"Repr\\u00e9sentante de la Fondation Hirondelle en Ukraine\",\"text\":\"Sabra Ayres est repr\\u00e9sentante de la Fondation Hirondelle en Ukraine depuis avril 2025, o\\u00f9 elle coordonne et met en \\u0153uvre des programmes de formation et de soutien destin\\u00e9s aux journalistes locaux ind\\u00e9pendants, en particulier ceux qui travaillent sur le terrain. Sabra a rejoint l'organisation en avril 2023 en tant que mentor dans le domaine des m\\u00e9dias. En tant que journaliste, Sabra a particuli\\u00e8rement \\u00e9crit sur l'Ukraine, la Russie et l'Europe de l'Est. Elle a couvert l'Ukraine de 2013 \\u00e0 2017, notamment la r\\u00e9volution de Ma\\u00efdan, l'annexion de la Crim\\u00e9e par la Russie et le d\\u00e9but de la guerre dans le Donbass. De 2017 \\u00e0 2020, elle a \\u00e9t\\u00e9 correspondante \\u00e0 Moscou pour le Los Angeles Times, couvrant l'actualit\\u00e9 en Russie et en Ukraine, ainsi qu'en Arm\\u00e9nie, en Moldavie, en Azerba\\u00efdjan et dans les r\\u00e9publiques d'Asie centrale. Sabra a enseign\\u00e9 le journalisme \\u00e0 l'Universit\\u00e9 am\\u00e9ricaine d'Afghanistan \\u00e0 Kaboul de 2011 \\u00e0 2013, et a \\u00e9t\\u00e9 professeure invit\\u00e9e \\u00e0 l'Institut indien de journalisme et des nouveaux m\\u00e9dias \\u00e0 Bangalore en 2009-2010. Ses articles ont \\u00e9t\\u00e9 publi\\u00e9s dans Vanity Fair, The Guardian, Christian Science Monitor, Al Jazeera America, Columbia Journalism Review et The New Republic, et elle a \\u00e9t\\u00e9 invit\\u00e9e sur CNN, NPR et BBC Radio. Elle a re\\u00e7u le Front Page Award 2016 de la meilleure correspondante \\u00e9trang\\u00e8re et a \\u00e9t\\u00e9 membre de l'International Women's Media Foundation en 2016. Ses reportages depuis l'Ukraine pour le Los Angeles Times ont \\u00e9t\\u00e9 inclus dans l'anthologie 2025 Best American Newspaper Narratives.\"},{\"name\":\"Nicki Bailey\",\"title\":\"Responsable SERA\",\"text\":\"Nicki Bailey est Responsable SERA (suivi, \\u00e9valuation, redevabilit\\u00e9 et apprentissage) \\u00e0 la Fondation Hirondelle. Nicki a rejoint la Fondation Hirondelle en 2023. Elle a plus de dix ans d\\u2019exp\\u00e9rience dans la recherche, le suivi et l\\u2019\\u00e9valuation des projets de m\\u00e9dias et de communication, particuli\\u00e8rement durant les crises humanitaires. Pendant huit ans, Nicki travaillait pour BBC Media Action, l\\u2019ONG de la BBC, en tant que responsable de recherche en Asie, o\\u00f9 elle collaborait avec les \\u00e9quipes de recherche en Afghanistan, au Bangladesh, au Cambodge, en Indon\\u00e9sie, au Myanmar et au N\\u00e9pal. Auparavant, Nicki \\u00e9tait responsable de la recherche et de l\\u2019apprentissage au si\\u00e8ge du CDAC (Communicating with Disaster Affected Communities) Network : un r\\u00e9seau d\\u2019organisations qui travaillent pour mieux communiquer avec les communaut\\u00e9s pendant les crises humanitaires, dont la Fondation Hirondelle fait partie. En 2011, elle \\u00e9t\\u00e9 responsable du suivi et de l\\u2019\\u00e9valuation pour l\\u2019ONG Merlin en R\\u00e9publique D\\u00e9mocratique du Congo o\\u00f9 elle a mis en place un syst\\u00e8me de suivi et d\\u2019\\u00e9valuation pour leurs projets de sant\\u00e9.\"},{\"name\":\"Pauline Bend\",\"title\":\"Responsable de programme\",\"text\":\"Pauline Bend est Responsable de programme \\u00e0 la Fondation Hirondelle depuis avril 2022. Elle a rejoint la Fondation Hirondelle en 2015 pour diriger le projet \\u00ab Studio Kalangou \\u00bb au Niger puis \\u00ab Studio Hirondelle RDC \\u00bb en R\\u00e9publique d\\u00e9mocratique du Congo. Avant cela, elle a travaill\\u00e9 dans le secteur du d\\u00e9veloppement et de l\\u2019appui aux m\\u00e9dias au sein de l\\u2019Institut Panos Afrique de l\\u2019Ouest, de 2006 \\u00e0 2015, o\\u00f9 elle a \\u00e9t\\u00e9 successivement Coordinatrice r\\u00e9gionale du Programme Pluralisme et D\\u00e9veloppement des M\\u00e9dias, puis Directrice des programmes. Elle a d\\u00e9but\\u00e9 sa carri\\u00e8re dans la diplomatie camerounaise entre 2005 et 2006. Pauline Bend a fait sa scolarit\\u00e9 au Cameroun avant de poursuivre des \\u00e9tudes sup\\u00e9rieures \\u00e0 l\\u2019Universit\\u00e9 catholique de Louvain en Belgique puis \\u00e0 l\\u2019Universit\\u00e9 de Rennes 2 et Paris 8 en France o\\u00f9 elle a obtenu un Doctorat en Sciences de l\\u2019information et de la communication.\"},{\"name\":\"Samir Bouaziz\",\"title\":\"Coordinateur national de la Fondation Hirondelle en Tunisie\",\"text\":\"Samir Bouaziz est coordinateur de projet pour la Fondation Hirondelle en Tunisie depuis mars 2024. Expert m\\u00e9dias et droits humains, il poss\\u00e8de plus de vingt-cinq ans d\\u2019exp\\u00e9rience professionnelle et une double expertise en journalisme et en plaidoyer pour les droits humains dans la r\\u00e9gion MENA. Samir a d\\u00e9but\\u00e9 sa carri\\u00e8re en tant que journaliste, collaborant avec divers m\\u00e9dias en Tunisie. Il a \\u00e9galement d\\u00e9velopp\\u00e9 une expertise dans la formation de journalistes, notamment sur la couverture des migrations fond\\u00e9e sur les droits humains et sur le traitement m\\u00e9diatique sensible au genre. Avant de rejoindre la Fondation, il a exerc\\u00e9 pendant plus de cinq ans comme responsable du plaidoyer pour l\\u2019Afrique du Nord chez Reporters sans fronti\\u00e8res (RSF). Son parcours comprend \\u00e9galement des postes de direction en communication, notamment en tant que responsable communication et campagnes \\u00e0 la section tunisienne d\\u2019Amnesty International et responsable de la communication \\u00e0 l\\u2019Institut Arabe des Droits de l'Homme. Samir est titulaire d\\u2019une ma\\u00eetrise en langue et litt\\u00e9rature arabes.\"},{\"name\":\"Colin Cogitore\",\"title\":\"Repr\\u00e9sentant UE\",\"text\":\"Colin Cogitore est le repr\\u00e9sentant de la Fondation Hirondelle aupr\\u00e8s de l\\u2019Union europ\\u00e9enne, bas\\u00e9 \\u00e0 Bruxelles. Il a commenc\\u00e9 \\u00e0 travailler pour la Fondation Hirondelle en avril 2020 pour suivre les affaires europ\\u00e9ennes et les partenariats. Colin a pr\\u00e9c\\u00e9demment travaill\\u00e9 en tant que Charg\\u00e9 de mission junior au Bureau europ\\u00e9en de liaison pour la consolidation de la paix (EPLO) sur des questions li\\u00e9es au financement de la consolidation de la paix, aux institutions et politiques de l\\u2019UE, \\u00e0 la paix et \\u00e0 la s\\u00e9curit\\u00e9 li\\u00e9es au genre, \\u00e0 l\\u2019alerte pr\\u00e9coce, aux relations UE-Afrique et \\u00e0 la liaison avec le Parlement europ\\u00e9en. Colin a \\u00e9galement effectu\\u00e9 plusieurs stages dans de grandes organisations de consolidation de la paix. Il est dipl\\u00f4m\\u00e9 de l\\u2019Institut pour la paix et les conflits de Grenade et de l\\u2019Universit\\u00e9 libre de Bruxelles.\"},{\"name\":\"Thierry Cruvellier\",\"title\":\"R\\u00e9dacteur en chef, Justice Info\",\"text\":\"Thierry Cruvellier est r\\u00e9dacteur en chef de Justiceinfo.net, m\\u00e9dia en ligne de la Fondation Hirondelle consacr\\u00e9 \\u00e0 la justice internationale et transitionnelle, depuis septembre 2018. Depuis trente ans, il couvre les proc\\u00e8s pour crimes contre l\\u2019humanit\\u00e9 et g\\u00e9nocide, du Rwanda \\u00e0 la Sierra Leone, de l\\u2019ex-Yougoslavie au Cambodge ou \\u00e0 la Colombie. Entre 1990 et 1996, Thierry Cruvellier a r\\u00e9guli\\u00e8rement couvert la guerre en Sierra Leone. Il \\u00e9tait aussi le repr\\u00e9sentant de Reporters sans fronti\\u00e8res dans la r\\u00e9gion des Grands lacs (Rwanda, Burundi, Congo, Ouganda) en 1994-1995. Il a \\u00e9t\\u00e9 r\\u00e9dacteur en chef du journal en ligne International Justice Tribune et a collabor\\u00e9 au New York Times. Titulaire d\\u2019une ma\\u00eetrise de journalisme \\u00e0 l\\u2019universit\\u00e9 de la Sorbonne (Paris), Thierry Cruvellier est laur\\u00e9at en 2003 de la prestigieuse bourse de la Fondation Nieman pour le journalisme \\u00e0 l\\u2019universit\\u00e9 d\\u2019Harvard. Ancien consultant aupr\\u00e8s des organisations non gouvernementales International Crisis Group et International Center for Transitional Justice, il a conduit de nombreux programmes de formation de journalistes \\u00e0 la couverture des proc\\u00e8s pour crimes contre l\\u2019humanit\\u00e9. Il a enseign\\u00e9 \\u00e0 l\\u2019universit\\u00e9 du Wisconsin-Madison, aux \\u00c9tats-Unis, et est l\\u2019auteur de trois livres : Le Tribunal des vaincus (Calmann-L\\u00e9vy, 2006), sur les proc\\u00e8s du g\\u00e9nocide au Rwanda, Le Ma\\u00eetre des aveux (Gallimard, 2011), sur les proc\\u00e8s des Khmers rouges au Cambodge, et Terre promise (Gallimard, 2018), r\\u00e9cit sur l\\u2019extraordinaire endurance du peuple sierra l\\u00e9onais au cours des quarante derni\\u00e8res ann\\u00e9es.\"},{\"name\":\"Olympe Dossa\",\"title\":\"Repr\\u00e9sentant de la Fondation Hirondelle au B\\u00e9nin\",\"text\":\"Olympe Dossa est sp\\u00e9cialiste en gestion de projets et de programmes. Il a rejoint la Fondation Hirondelle en 2024, o\\u00f9 il occupe actuellement le poste de Repr\\u00e9sentant national au B\\u00e9nin. Au cours de quinze ann\\u00e9es d\\u2019exp\\u00e9rience, il a notamment pilot\\u00e9 et coordonn\\u00e9 des projets dans des domaines vari\\u00e9s tels que la sant\\u00e9, l\\u2019\\u00e9ducation, le genre, ainsi que le secteur des m\\u00e9dias. Au cours de sa carri\\u00e8re, il a travaill\\u00e9 au sein de plusieurs organisations, notamment \\u00e0 Population Services International (PSI) et \\u00e0 WeWorld, o\\u00f9 il a exerc\\u00e9 entre autres, les fonctions de Directeur des programmes au B\\u00e9nin. Il est titulaire d\\u2019un Master en contr\\u00f4le de gestion et audit obtenu \\u00e0 l\\u2019\\u00c9cole nationale d\\u2019\\u00e9conomie appliqu\\u00e9e et de management de l\\u2019Universit\\u00e9 du B\\u00e9nin.\"},{\"name\":\"Karine Dyskiewicz\",\"title\":\"Repr\\u00e9sentante de la Fondation Hirondelle au Niger\",\"text\":\"Karine Dyskiewicz est Repr\\u00e9sentante de la Fondation Hirondelle au Niger depuis novembre 2021, o\\u00f9 elle supervise la mise en \\u0153uvre du projet Studio Kalangou. Forte d\\u2019une solide exp\\u00e9rience dans la coordination et la direction de programmes humanitaires et de d\\u00e9veloppement, elle a occup\\u00e9 plusieurs postes \\u00e0 responsabilit\\u00e9s au Niger, aupr\\u00e8s de l\\u2019ONG allemande ASB Niger, de M\\u00e9decins du Monde France et de la Croix-Rouge fran\\u00e7aise. Elle a \\u00e9galement travaill\\u00e9 comme consultante pour la GIZ et le Programme Alimentaire Mondial (PAM). Titulaire d\\u2019un BTS Marketing\\\/Actions commerciales, elle a suivi plusieurs formations en planification de projet, gestion d\\u2019\\u00e9quipe et gestion financi\\u00e8re.\"},{\"name\":\"Sandra Fontaine\",\"title\":\"Responsable de programme\",\"text\":\"Sandra Fontaine est Responsable de programme \\u00e0 la Fondation Hirondelle. Elle s\\u2019occupe du d\\u00e9veloppement des nouveaux projets, de la strat\\u00e9gie de renforcement des m\\u00e9dias partenaires, ainsi que du projet Justice Info, et des activit\\u00e9s en Tunisie et Asie du Sud-Est (Myanmar, Pakistan). Sandra Fontaine a rejoint la Fondation Hirondelle en mars 2018. Elle b\\u00e9n\\u00e9ficie de plus de 15 ans d\\u2019exp\\u00e9rience comme journaliste, et g\\u00e8re des projets de media development depuis 2016, d\\u2019abord pour Canal France International, l\\u2019agence fran\\u00e7aise de coop\\u00e9ration m\\u00e9dia. Elle a pr\\u00e9c\\u00e9demment travaill\\u00e9 comme R\\u00e9dactrice en chef adjointe de l\\u2019agence de presse InfoSud \\u00e0 Gen\\u00e8ve pour couvrir l\\u2019actualit\\u00e9 des droits humains, et comme reporter en Afrique. Elle a \\u00e9galement \\u00e9t\\u00e9 la r\\u00e9dactrice en chef du magazine culturel Souffle d\\u2019Afrique. Elle a d\\u00e9but\\u00e9 sa carri\\u00e8re comme journaliste au quotidien r\\u00e9gional Le Dauphin\\u00e9 Lib\\u00e9r\\u00e9 en France. Sandra Fontaine est titulaire d\\u2019un Master en journalisme de l\\u2019ESJ (Ecole sup\\u00e9rieure de journalisme) Paris.\"},{\"name\":\"Julie Godignon\",\"title\":\"Responsable de programme\",\"text\":\"Julie Godignon est Responsable de programme \\u00e0 la Fondation Hirondelle. Elle supervise  les projets de la Fondation Hirondelle en Asie. Elle a rejoint la fondation en 2016 en tant que charg\\u00e9e d\\u2019op\\u00e9ration. Ponctuellement, elle m\\u00e8ne aussi des missions d\\u2019\\u00e9valuation, d\\u2019\\u00e9tude de faisabilit\\u00e9 et d\\u2019impact pour d\\u2019autres organisations. Pr\\u00e9c\\u00e9demment, elle a travaill\\u00e9 dans le secteur de l\\u2019aide au d\\u00e9veloppement des m\\u00e9dias dans des pays dits fragiles ou en crise, en Indon\\u00e9sie, au Vietnam mais aussi au Minist\\u00e8re fran\\u00e7ais des affaires \\u00e9trang\\u00e8res et aupr\\u00e8s de diverses organisations telles que l\\u2019OSCE, l\\u2019OIF et la BBC Media Action. Elle a d\\u00e9but\\u00e9 sa carri\\u00e8re en d\\u00e9veloppant des programmes \\u00e9ducatifs et d\\u2019initiation au langage audiovisuel \\u00e0 l\\u2019attention de jeunes publics et de migrants. Julie Godignon est titulaire d\\u2019un Master en production et r\\u00e9alisation de documentaire audiovisuel.\"},{\"name\":\"Eve Konan\",\"title\":\"Responsable de programme\",\"text\":\"Eve Konan est Responsable de programme pour la Fondation Hirondelle, au si\\u00e8ge \\u00e0 Lausanne, depuis mars 2023. Elle a pr\\u00e9c\\u00e9demment supervis\\u00e9 la mise en \\u0153uvre des projets en Centrafrique, au sein de Radio Ndeke Luka, dont elle g\\u00e9rait aussi les activit\\u00e9s de la r\\u00e9gie publicitaire. Eve a pr\\u00e9c\\u00e9demment travaill\\u00e9 pendant cinq ans pour l\\u2019ONG fran\\u00e7aise Bioforce comme charg\\u00e9e de projet au si\\u00e8ge puis coordinatrice de projet \\u00e0 Bangui en RCA. Dipl\\u00f4m\\u00e9e en relations internationales (Universit\\u00e9 Jean Moulin Lyon III) et plus r\\u00e9cemment d\\u2019un master en Management (EM Lyon), Eve a d\\u00e9marr\\u00e9 sa carri\\u00e8re dans l\\u2019agence Business France de Johannesburg, puis comme attach\\u00e9e de presse pour la Ville de Lyon, en France.\"},{\"name\":\"Gilles Magnin\",\"title\":\"Responsable de programme\",\"text\":\"Gilles Magnin est Responsable de Programme \\u00e0 la Fondation Hirondelle depuis Mai 2018. Il supervise actuellement les projets de la Fondation Hirondelle en R\\u00e9publique centrafricaine (Radio Ndeke Luka) et au Burundi. Il a \\u00e9galement assur\\u00e9 en 2019 pour la Fondation Hirondelle un mandat de 6 mois en tant que logisticien-administrateur en R\\u00e9publique d\\u00e9mocratique du Congo dans la ville de Kananga. Il a pr\\u00e9c\\u00e9demment travaill\\u00e9 au sein de la Fondation Id\\u00e9es Sport \\u00e0 Berne o\\u00f9 il \\u00e9tait responsable de projet. Gilles Magnin est titulaire d\\u2019un Master en Politiques Africaines de l\\u2019Universit\\u00e9 de Londres, et d\\u2019un Bachelor en Science Politique de l\\u2019Universit\\u00e9 de Lausanne.\"},{\"name\":\"Mariama Sawadogo\",\"title\":\"Repr\\u00e9sentante de la Fondation Hirondelle au Mali\",\"text\":\"Mariama Sawadogo travaille depuis plus de quinze ans dans le secteur humanitaire et du d\\u00e9veloppement. Elle a collabor\\u00e9 avec des organisations telles que Search for Common Ground, Mercy Corps, CARE International et le Conseil danois pour les r\\u00e9fugi\\u00e9s dans plusieurs pays du Sahel et d\\u2019Afrique centrale. Sp\\u00e9cialiste de la coh\\u00e9sion sociale, du genre et de l\\u2019inclusion, de la gestion des conflits et de la consolidation de la paix, elle est \\u00e9galement formatrice pour l\\u2019\\u00c9cole de Maintien de la Paix Alioune Blondin Beye (EMP-ABB) et le Centre de Comp\\u00e9tence en N\\u00e9gociation Humanitaire (CCHN). Elle est dipl\\u00f4m\\u00e9e d\\u2019un Master II en Gestion de conflits et consolidation de la paix de l\\u2019Institut Sup\\u00e9rieur en S\\u00e9curit\\u00e9 Humaine du Burkina Faso (ISSH) et a obtenu une certification en leadership et gouvernance des organisations ISO 37000 \\u00e0 l'institut africain de Formation et de Recherche-Action Humanitaire et D\\u00e9veloppement (IAFR-AHD)\"},{\"name\":\"Thibaud Oberli\",\"title\":\"Charg\\u00e9 d\\u2019Op\\u00e9rations\",\"text\":\"Thibaud Oberli est Charg\\u00e9 d\\u2019Op\\u00e9rations \\u00e0 la Fondation Hirondelle depuis Mai 2023. Il supervise le projet de formation transversal \\u00ab Pr\\u00e9vention de la violence et M\\u00e9dias \\u00bb et soutien le service de communication de la Fondation Hirondelle. Il a pr\\u00e9c\\u00e9demment travaill\\u00e9 en tant que journaliste sportif et \\u00e9ditionneur pour les titres romands de TX Group, anciennement Tamedia (24 Heures, la Tribune de Gen\\u00e8ve, 20 Minutes, lematin.ch), et comme pigiste pour la radio locale RTN. Thibaud Oberli est titulaire d\\u2019un Master en \\u00c9tudes Africaines de l\\u2019Universit\\u00e9 de Gen\\u00e8ve et d\\u2019un Bachelor en Science Politique de l\\u2019Universit\\u00e9 de Lausanne.\"},{\"name\":\"Laourou Koudoussou\",\"title\":\"Repr\\u00e9sentant de la Fondation Hirondelle - Burkina Faso\",\"text\":\"Koudoussou Ad\\u00e9china Laourou dirige les activit\\u00e9s de la Fondation Hirondelle au Burkina Faso depuis f\\u00e9vrier 2025. Il supervise la mise en \\u0153uvre du programme Studio Yafa et encadre une \\u00e9quipe de 50 collaborateurs. Fort de plus de douze ans d\\u2019exp\\u00e9rience dans la gestion et la coordination de projets humanitaires et de d\\u00e9veloppement en Afrique de l\\u2019Ouest, il a occup\\u00e9 des fonctions cl\\u00e9s de direction et de coordination au sein d\\u2019organisations telles que l\\u2019ONG internationale EmpowHer, l\\u2019Association IMINRIO et le Programme PAOSU. Sp\\u00e9cialiste des questions de genre et d\\u2019inclusion, il est \\u00e9galement reconnu pour son expertise en mobilisation de financements multi-bailleurs et en leadership d\\u2019\\u00e9quipe. Consultant-formateur international, il a accompagn\\u00e9 des acteurs \\u00e9tatiques et des ONG en Guin\\u00e9e, au B\\u00e9nin et au Burkina Faso sur les enjeux d\\u2019\\u00e9galit\\u00e9, d\\u2019autonomisation des femmes et de transformation organisationnelle. Il est titulaire d\\u2019un master en Coop\\u00e9ration internationale et Aide humanitaire obtenu \\u00e0 Kalu Institute (Espagne) et termine actuellement un Global Executive Master en Management \\u00e0 HEC Paris.\"},{\"name\":\"Zara Yacoub\",\"title\":\"Repr\\u00e9sentante de la Fondation Hirondelle - Tchad\",\"text\":\"Zara Mahamat Yacoub a rejoint la Fondation Hirondelle en mars 2025, o\\u00f9 elle a contribu\\u00e9 \\u00e0 la mise en place du Studio Hirondelle Tchad. Ancienne directrice pays de l\\u2019ONG am\\u00e9ricaine Equal Access et directrice g\\u00e9n\\u00e9rale de Sud Cap Production, elle a \\u00e9galement travaill\\u00e9 comme journaliste r\\u00e9alisatrice \\u00e0 Channel Africa TV en Afrique du Sud ainsi qu\\u2019\\u00e0 la Radio et T\\u00e9l\\u00e9vision nationales du Tchad. Elle a r\\u00e9alis\\u00e9 plusieurs films, dont certains ont \\u00e9t\\u00e9 prim\\u00e9s aux \\u00c9tats-Unis, au Canada et en Afrique. Zara est \\u00e9galement \\u00e0 l\\u2019origine de la premi\\u00e8re radio libre au Tchad. Membre de plusieurs associations professionnelles nationales et internationales, elle intervient comme formatrice et consultante. Elle est titulaire d\\u2019une licence en lettres modernes de l\\u2019Universit\\u00e9 du Tchad, d\\u2019un dipl\\u00f4me en communication audiovisuelle de l\\u2019Institut national de la communication audiovisuelle en France et d\\u2019un Master II en management des m\\u00e9dias de l\\u2019\\u00c9cole de journalisme de Lille. Elle a par ailleurs suivi de nombreuses formations en journalisme, radio et cin\\u00e9ma \\u00e0 travers le monde.\"}]},\"support\":{\"title\":\"Services (*)\",\"members\":[{\"name\":\"Jim Bodeman\",\"title\":\"Contr\\u00f4leur de gestion\",\"text\":\"Jim Bodeman est Contr\\u00f4leur de gestion \\u00e0 la Fondation Hirondelle depuis juin 2014. Il assure principalement le suivi administratif et financier de projets. Il est aussi responsable de l\\u2019organisation des voyages et de la v\\u00e9rification de la conformit\\u00e9 des audits et proc\\u00e9dures d\\u2019achat.\"},{\"name\":\"Pablo Diserens\",\"title\":\"Charg\\u00e9 de philanthropie\",\"text\":\"Pablo Diserens est sp\\u00e9cialiste en strat\\u00e9gie digitale. Il a rejoint la Fondation Hirondelle en 2025. Depuis plus de 10 ans, il met ses comp\\u00e9tences en marketing digital au service de petites et grandes ONGs s\\u2019engageant avec passion pour des causes qui lui tiennent \\u00e0 c\\u0153ur. Son expertise cr\\u00e9e des ponts entre innovation num\\u00e9rique et impact social, pla\\u00e7ant toujours l\\u2019humain et ses valeurs fondamentales au centre de chaque projet qu\\u2019il entreprend.\"},{\"name\":\"Malonga Luzemo\",\"title\":\"Apprenti employ\\u00e9 de commerce\",\"text\":\"Depuis ao\\u00fbt 2025, Malonga Luzemo a int\\u00e9gr\\u00e9 la Fondation Hirondelle en tant qu\\u2019apprenti employ\\u00e9 de commerce. Pour les deux prochaines ann\\u00e9es, il navigue entre la comptabilit\\u00e9 avec R\\u00e9gis et les Ressources humaines avec H\\u00e9l\\u00e8ne, en apportant son aide et sa motivation au quotidien.\"},{\"name\":\"R\\u00e9gis Gomez\",\"title\":\"Comptable\",\"text\":\"R\\u00e9gis Gomez est Comptable \\u00e0 la Fondation Hirondelle depuis d\\u00e9cembre 2022. Titulaire d\\u2019un Brevet de technicien sup\\u00e9rieur en Comptabilit\\u00e9 et Gestion des Administrations, il a travaill\\u00e9 en tant que comptable dans divers secteurs d\\u2019activit\\u00e9 : banques, assurances (BNP, Axa, Cofincor), transport maritime (CMA CGM), m\\u00e9dical (Cermavein). Il a ainsi cumul\\u00e9 plus d\\u2019une quinzaine d\\u2019ann\\u00e9es d\\u2019exp\\u00e9rience en tant que comptable. Parmi ces diverses comp\\u00e9tences, R\\u00e9gis Gomez s\\u2019est sp\\u00e9cialis\\u00e9 en maitrise d\\u2019ouvrage en ayant une formation de chef de projet digital.\"},{\"name\":\"Christelle Greffier\",\"title\":\"Assistante administrative\",\"text\":\"Christelle Greffier est assistante administrative et secr\\u00e9taire du Conseil de Fondation \\u00e0 la Fondation Hirondelle depuis janvier 2022. Avec pr\\u00e8s de 15 ans d\\u2019exp\\u00e9rience comme Business Travel Agent dans le voyage humanitaire notamment chez M\\u00e9decins Sans Fronti\\u00e8res \\u00e0 Gen\\u00e8ve, elle peut assurer le soutien administratif et logistique au si\\u00e8ge de la Fondation. Elle a \\u00e9galement travaill\\u00e9 comme Administratrice ressources humaines terrain et Administratrice learning and development pour MSF.\"},{\"name\":\"Lo\\u00efc Joliat\",\"title\":\"Responsable Technique, IT et Web\",\"text\":\"Lo\\u00efc Joliat a rejoint la Fondation Hirondelle en avril 2020 en tant que technicien IT et son. \\u00c0 ce poste, il contribue au bon fonctionnement des ressources informatiques, techniques et de production, aussi bien au si\\u00e8ge que sur les terrains d\\u2019intervention. En 2022, il devient Responsable technique, IT & Web. Il assure alors le pilotage de ces domaines, d\\u00e9finit les orientations strat\\u00e9giques dans le cadre fix\\u00e9 par la direction et agit comme point focal pour les responsables techniques des diff\\u00e9rents projets. Auparavant, Lo\\u00efc Joliat a \\u00e9volu\\u00e9 dans le secteur de l\\u2019audio professionnel, notamment au sein d\\u2019entreprises de prestation technique. \\u00c9lectronicien de formation, titulaire d\\u2019un brevet f\\u00e9d\\u00e9ral, il est \\u00e9galement engag\\u00e9 depuis plusieurs ann\\u00e9es dans la formation initiale en tant qu\\u2019expert aux examens de technisc\\u00e9niste et membre de la commission de qualification.\"},{\"name\":\"Chlo\\u00e9 Gagnaire\",\"title\":\"Contr\\u00f4leuse de gestion\",\"text\":\"Chlo\\u00e9 Gagnaire est contr\\u00f4leuse de gestion \\u00e0 la Fondation Hirondelle depuis septembre 2025. Elle y assure le suivi financier des projets terrain de la Fondation. Avant de rejoindre la Fondation Hirondelle, elle a travaill\\u00e9 au si\\u00e8ge de Terre des Hommes Lausanne, d\\u2019abord en tant que contr\\u00f4leuse de gestion, puis comme sp\\u00e9cialiste finance. \\u00c0 ce poste, elle a notamment contribu\\u00e9 au d\\u00e9veloppement du Manuel Finance et d\\u00e9velopp\\u00e9 des formations \\u00e0 destination des \\u00e9quipes financi\\u00e8res. Auparavant, Chlo\\u00e9 a pass\\u00e9 une dizaine d\\u2019ann\\u00e9es sur le terrain dans divers contextes humanitaires (Ha\\u00efti, Tchad, RDC, Soudan du Sud, \\u00c9thiopie, Syrie, Liban, Jordanie, Irak), o\\u00f9 elle a principalement occup\\u00e9 les fonctions de coordinatrice finance ou support.Elle est titulaire d\\u2019un Master en Business et Administration obtenu \\u00e0 l\\u2019ICN Business School de Nancy.\"},{\"name\":\"Cephas Miningou\",\"title\":\"Contr\\u00f4leur de gestion\",\"text\":\"C\\u00e9phas Miningou est Contr\\u00f4leur de gestion \\u00e0 la Fondation Hirondelle depuis d\\u00e9cembre 2022. Il assure le suivi administratif et financier des projets. Pr\\u00e9c\\u00e9demment, C\\u00e9phas Miningou a travaill\\u00e9 notamment en tant qu\\u2019auditeur interne aupr\\u00e8s de l\\u2019organisation internationale \\u00e0 but non lucratif Unbound bas\\u00e9e \\u00e0 Kansas City et \\u00e9galement comme team leader des partenaires financiers dans le d\\u00e9partement des finances au sein de Medair \\u00e0 Ecublens. Il est titulaire d\\u2019un Master en d\\u00e9veloppement international.\"},{\"name\":\"Nicholas Mansson\",\"title\":\"Responsable finances\",\"text\":\"Nicholas Mansson est responsable finance \\u00e0 la Fondation Hirondelle depuis Septembre 2022. Il assure la qualit\\u00e9 financi\\u00e8re globale des projets et activit\\u00e9s de la Fondation Hirondelle. Il avait rejoint la Fondation Hirondelle en septembre 2020 comme contr\\u00f4leur de gestion. Pr\\u00e9c\\u00e9demment, Nicholas Mansson a travaill\\u00e9 pour M\\u00e9decins sans fronti\\u00e8res - Suisse comme Finance & HR Team Leader et Project Finance & HR Manager au Cameroun et Niger. Il a \\u00e9galement travaill\\u00e9, en Suisse et sur le terrain (Irak, Syrie, Tchad) pour CARE International comme Finance & Admin Officer et gestionnaire des supports d\\u00e9ployable. Nicholas Mansson est titulaire d\\u2019un Bachelor en Business Administration\\\/Management \\u00e0 HEC Lausanne & ICADE Madrid.\"},{\"name\":\"Olivier Roussel\",\"title\":\"Contr\\u00f4leur de gestion\",\"text\":\"Olivier Roussel est contr\\u00f4leur de gestion \\u00e0 la Fondation Hirondelle depuis 2022. Il y assure le suivi des supports sur les projets terrain de la Fondation Hirondelle. Pr\\u00e9c\\u00e9demment, Olivier Roussel a travaill\\u00e9 plusieurs ann\\u00e9es sur le terrain \\u00e0 la fois dans la gestion de projet et la gestion administrative et financi\\u00e8re en tant que Coordinateur terrain et Coordinateur administratif au sein de diff\\u00e9rentes ONG Fran\\u00e7aises ainsi que la Croix Rouge. Il est titulaire d\\u2019un Bachelor en management avec une sp\\u00e9cialisation en Finance.\"},{\"name\":\"H\\u00e9l\\u00e8ne Maillet\",\"title\":\"Sp\\u00e9cialiste Ressources Humaines\",\"text\":\"H\\u00e9l\\u00e8ne Maillet est Sp\\u00e9cialiste RH \\u00e0 la Fondation Hirondelle. Elle est l\\u2019interlocutrice cl\\u00e9 pour toutes les questions li\\u00e9es aux ressources humaines au si\\u00e8ge, veillant \\u00e0 la gestion fluide des dossiers au quotidien tout en contribuant activement \\u00e0 l\\u2019am\\u00e9lioration des politiques et pratiques RH de l\\u2019organisation. Avec plus de 12 ans d\\u2019exp\\u00e9rience dans le domaine des ressources humaines, notamment \\u00e0 l\\u2019Association CHS Alliance et en start-up, elle allie expertise technique et sens humain. Son parcours l\\u2019a \\u00e9galement conduite sur le terrain, o\\u00f9 elle a exerc\\u00e9 comme d\\u00e9l\\u00e9gu\\u00e9e polyvalente pour le CICR en R\\u00e9publique D\\u00e9mocratique du Congo. H\\u00e9l\\u00e8ne est titulaire d\\u2019un Master en droit et du brevet f\\u00e9d\\u00e9ral de sp\\u00e9cialiste en ressources humaines.\"}]}};\r\n\t<\/script>\r\n\t<h3 class=\"wp-block-heading\">Direction<\/h3><div class=\"row team-group\"><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"direction-0\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/caroline-vuillemin.jpg\" alt=\"Caroline Vuillemin\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Caroline Vuillemin<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Directrice g\u00e9n\u00e9rale<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"direction-1\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/nicolas-boissez.jpg\" alt=\"Nicolas Boissez\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Nicolas Boissez<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Directeur des op\u00e9rations<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"direction-2\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/christyl-vasserot.jpg\" alt=\"Christyl Vasserot\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Christyl Vasserot<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Directrice des supports et d\u00e9veloppement institutionnel<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/div><h3 class=\"wp-block-heading\">\u00c9ditorial \/ Communication \/ Recherche<\/h3><div class=\"row team-group\"><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"editorial-0\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/jacqueline-dalton.jpg\" alt=\"Jacqueline Dalton\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Jacqueline Dalton<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Responsable \u00e9ditoriale<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"editorial-1\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/julie-crenn.jpg\" alt=\"Julie Crenn\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Julie Crenn<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Sp\u00e9cialiste Communication<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"editorial-2\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/sacha-meuter.jpg\" alt=\"Sacha Meuter\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Sacha Meuter<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Responsable de la recherche et des politiques<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/div><h3 class=\"wp-block-heading\">Op\u00e9rations (*)<\/h3><div class=\"row team-group\"><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-0\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/ouboule-abalo.jpg\" alt=\"Ouboul\u00e9 Abalo\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Ouboul\u00e9 Abalo<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Repr\u00e9sentant de la Fondation Hirondelle en R\u00e9publique centrafricaine<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-1\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/sabra-ayres.jpg\" alt=\"Sabra Ayres\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Sabra Ayres<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Repr\u00e9sentante de la Fondation Hirondelle en Ukraine<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-2\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/nicki-bailey.jpg\" alt=\"Nicki Bailey\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Nicki Bailey<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Responsable SERA<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-3\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/pauline-bend.jpg\" alt=\"Pauline Bend\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Pauline Bend<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Responsable de programme<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/div> <div class=\"row team-group\"><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-4\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/samir-bouaziz.jpg\" alt=\"Samir Bouaziz\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Samir Bouaziz<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Coordinateur national de la Fondation Hirondelle en Tunisie<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-5\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/colin-cogitore.jpg\" alt=\"Colin Cogitore\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Colin Cogitore<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Repr\u00e9sentant UE<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-6\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/thierry-cruvellier.jpg\" alt=\"Thierry Cruvellier\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Thierry Cruvellier<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">R\u00e9dacteur en chef, Justice Info<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-7\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/olympe-dossa.jpg\" alt=\"Olympe Dossa\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Olympe Dossa<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Repr\u00e9sentant de la Fondation Hirondelle au B\u00e9nin<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/div> <div class=\"row team-group\"><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-8\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/karine-dyskiewicz.jpg\" alt=\"Karine Dyskiewicz\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Karine Dyskiewicz<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Repr\u00e9sentante de la Fondation Hirondelle au Niger<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-9\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/sandra-fontaine.jpg\" alt=\"Sandra Fontaine\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Sandra Fontaine<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Responsable de programme<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-10\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/julie-godignon.jpg\" alt=\"Julie Godignon\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Julie Godignon<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Responsable de programme<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-11\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/eve-konan.jpg\" alt=\"Eve Konan\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Eve Konan<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Responsable de programme<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/div> <div class=\"row team-group\"><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-12\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/gilles-magnin.jpg\" alt=\"Gilles Magnin\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Gilles Magnin<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Responsable de programme<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-13\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/mariama-sawadogo.jpg\" alt=\"Mariama Sawadogo\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Mariama Sawadogo<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Repr\u00e9sentante de la Fondation Hirondelle au Mali<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-14\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/thibaud-oberli.jpg\" alt=\"Thibaud Oberli\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Thibaud Oberli<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Charg\u00e9 d\u2019Op\u00e9rations<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-15\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/laourou-koudoussou.jpg\" alt=\"Laourou Koudoussou\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Laourou Koudoussou<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Repr\u00e9sentant de la Fondation Hirondelle - Burkina Faso<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/div> <div class=\"row team-group\"><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"operations-16\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/zara-yacoub.jpg\" alt=\"Zara Yacoub\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Zara Yacoub<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Repr\u00e9sentante de la Fondation Hirondelle - Tchad<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/div><h3 class=\"wp-block-heading\">Services (*)<\/h3><div class=\"row team-group\"><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-0\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/jim-bodeman.jpg\" alt=\"Jim Bodeman\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Jim Bodeman<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Contr\u00f4leur de gestion<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-1\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/pablo-diserens.jpg\" alt=\"Pablo Diserens\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Pablo Diserens<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Charg\u00e9 de philanthropie<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-2\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/malonga-luzemo.jpg\" alt=\"Malonga Luzemo\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Malonga Luzemo<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Apprenti employ\u00e9 de commerce<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-3\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/regis-gomez.jpg\" alt=\"R\u00e9gis Gomez\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>R\u00e9gis Gomez<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Comptable<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/div> <div class=\"row team-group\"><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-4\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/christelle-greffier.jpg\" alt=\"Christelle Greffier\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Christelle Greffier<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Assistante administrative<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-5\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/loic-joliat.jpg\" alt=\"Lo\u00efc Joliat\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Lo\u00efc Joliat<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Responsable Technique, IT et Web<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-6\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/chloe-gagnaire.jpg\" alt=\"Chlo\u00e9 Gagnaire\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Chlo\u00e9 Gagnaire<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Contr\u00f4leuse de gestion<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-7\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/cephas-miningou.jpg\" alt=\"Cephas Miningou\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Cephas Miningou<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Contr\u00f4leur de gestion<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/div> <div class=\"row team-group\"><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-8\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/nicholas-mansson.jpg\" alt=\"Nicholas Mansson\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Nicholas Mansson<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Responsable finances<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-9\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/olivier-roussel.jpg\" alt=\"Olivier Roussel\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>Olivier Roussel<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Contr\u00f4leur de gestion<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><div class=\"team-wrap team-wrap--nosocial col-md-3 col-sm-6\" style=\"cursor:pointer;\" data-openmodaltext=\"support-10\"\"><div class=\"team-img\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hirondelle.org\/wp-content\/themes\/hirondelle\/assets\/image\/new-pictures\/helene-maillet.jpg\" alt=\"H\u00e9l\u00e8ne Maillet\" \/>\r\n\t\t\t\t\t\t\t<\/div><div class=\"team-content\">\r\n\t\t\t\t\t\t\t\t<h4>H\u00e9l\u00e8ne Maillet<\/h4>\r\n\t\t\t\t\t\t\t\t<span class=\"designation\">Sp\u00e9cialiste Ressources Humaines<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/div>\r\n\r\n\t<div id=\"FHTeamMemberModal\" class=\"modal fade\">\r\n\t\t<div class=\"modal-dialog modal-lg\">\r\n\t\t\t<div class=\"modal-content\">\r\n\t\t\t\t<div class=\"modal-header\">\r\n\t\t\t\t\t<div class=\"modal-title\"><\/div>\r\n\t\t\t\t\t<button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><\/button>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"modal-body\">\r\n\t\t\t\t\t<div class=\"modal-intro-image\">\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"\" class=\"modal-image\" \/>\r\n\t\t\t\t\t\t<p class=\"modal-intro\"><\/p>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"modal-text\"><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<script>\r\n\t\tjQuery(function(){\r\n\t\t\tjQuery(\"#FHTeamMemberModal\").insertAfter(\"#footer\");\r\n\t\r\n\t\t\tjQuery(\".team-wrap[data-openmodaltext]\").click(function(){\r\n\t\t\t\tvar tmp = jQuery(this).data(\"openmodaltext\").split(\"-\");\r\n\t\t\t\tvar group_key = tmp[0];\r\n\t\t\t\tvar member_key = tmp[1];\r\n\t\t\t\tvar member_configuration = team_configuration[group_key][\"members\"][member_key];\r\n\t\t\t\t\r\n\t\t\t\tjQuery(\"#FHTeamMemberModal .modal-title\").text(member_configuration[\"name\"]);\r\n\t\t\t\tjQuery(\"#FHTeamMemberModal .modal-image\").attr(\"src\", jQuery(\"img\", this).attr(\"src\"));\r\n\t\t\t\tjQuery(\"#FHTeamMemberModal .modal-intro\").text(member_configuration[\"title\"]);\r\n\t\t\t\tjQuery(\"#FHTeamMemberModal .modal-text\").html(member_configuration[\"text\"]);\r\n\t\t\t\tjQuery(\"#FHTeamMemberModal\").modal(\"show\");\r\n\t\t\t});\r\n\t\t\t\r\n\t\t});\r\n\t<\/script>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>* Nous mentionnons ici nos collaborateur\u00b7rice\u00b7s sous contrat suisse, bas\u00e9\u00b7e\u00b7s \u00e0 Lausanne ou sur le terrain. La Fondation Hirondelle s\u2019appuie par ailleurs sur plus de 250 coll\u00e8gues nationaux dans nos pays d\u2019intervention.<\/p>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/www.hirondelle.org\/wp-content\/uploads\/2026\/04\/Organigramme-avril26.pdf\">Organigramme de la Fondation Hirondelle<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>* Nous mentionnons ici nos collaborateur\u00b7rice\u00b7s sous contrat suisse, bas\u00e9\u00b7e\u00b7s \u00e0 Lausanne ou sur le terrain. La Fondation Hirondelle s\u2019appuie par ailleurs sur plus de 250 coll\u00e8gues nationaux dans nos pays d\u2019intervention.<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":212,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-248","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 23:52:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/pages\/248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=248"}],"version-history":[{"count":19,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/pages\/248\/revisions"}],"predecessor-version":[{"id":26853,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/pages\/248\/revisions\/26853"}],"up":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/pages\/212"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}