{"id":1255,"date":"2020-08-25T10:31:52","date_gmt":"2020-08-25T08:31:52","guid":{"rendered":"https:\/\/www.hirondelle.org\/studio-tamani-et-le-coup-d-etat-au-mali-le-defi-de-l-information-en-contexte-de-crise"},"modified":"2020-08-25T10:31:52","modified_gmt":"2020-08-25T08:31:52","slug":"studio-tamani-et-le-coup-d-etat-au-mali-le-defi-de-l-information-en-contexte-de-crise","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/studio-tamani-et-le-coup-d-etat-au-mali-le-defi-de-l-information-en-contexte-de-crise","title":{"rendered":"Studio Tamani et le Coup d&rsquo;\u00e9tat au Mali : le d\u00e9fi de l&rsquo;information quand \u00e9clate la crise"},"content":{"rendered":"<p><strong>Apr\u00e8s le Coup d&rsquo;\u00e9tat du 18 ao\u00fbt 2020 au Mali, la r\u00e9daction de Studio Tamani, le programme radio de la Fondation Hirondelle et de l&rsquo;URTEL au Mali, \u00e9value son action dans la couverture de ces \u00e9v\u00e9nements. Martin Faye, Repr\u00e9sentant de la Fondation Hirondelle au Mali, explique les d\u00e9fis et mesures prises pour permettre \u00e0 la r\u00e9daction de faire son travail sur place, dans ce contexte explosif.<\/strong><\/p>\n<p>\u00ab\u00a0Tout le monde en convient, d\u00e8s qu\u2019une crise \u00e9clate, les populations se tournent vers les m\u00e9dias pour savoir ce qui se passe exactement. Et dans ce domaine, la radio est la plus concern\u00e9e, parce qu&rsquo;elle est le m\u00e9dia le plus imm\u00e9diat, le plus rapide et aussi le plus \u00e9motionnel. En tous cas, le m\u00e9dia vers lequel on se tourne en premier lieu lors d&rsquo;une crise.<\/p>\n<p>La Fondation Hirondelle est une organisation suisse cr\u00e9\u00e9e en 1995, qui fournit de l\u2019information \u00e0 des populations confront\u00e9es \u00e0 des crises, pour leur permettre d\u2019agir dans leur vie quotidienne et citoyenne. Studio Tamani, cr\u00e9\u00e9e en 2013 par la Fondation Hirondelle et l&rsquo;URTEL (Union des radios et t\u00e9l\u00e9visions libres du Mali) diffuse chaque jour depuis Bamako un programme radiophonique, relay\u00e9 actuellement par 85 radios partenaires r\u00e9parties dans toutes les r\u00e9gions du Mali.\u00a0 La r\u00e9daction compos\u00e9e uniquement de jeunes journalistes maliens produit des journaux en 5 langues (bambara, tamashek, sonrha\u00ef, fran\u00e7ais, poular), et traite \u00e9galement dans les magazines et les d\u00e9bats, des probl\u00e9matiques de ce pays en crise depuis pr\u00e8s de dix ans.<\/p>\n<p>Le feu couvait depuis plusieurs semaines et le coup d\u2019\u00e9tat du 19 ao\u00fbt est en quelque sorte le point d\u2019orgue de mouvements de protestation contre le pouvoir en place. D\u00e8s le d\u00e9but, les leaders de la contestation ont r\u00e9clam\u00e9 sa d\u00e9mission du pr\u00e9sident Ibrahim Boubacar Keita.<br \/>A la Fondation Hirondelle, l\u2019\u00e9valuation fait partie de la cha\u00eene \u00e9ditoriale. Studio Tamani a-t-il \u00e9t\u00e9 neutre dans la couverture du coup d\u2019Etat ? Simple observateur des faits relat\u00e9s ? Le souci de l\u2019int\u00e9r\u00eat des populations ? V\u00e9rifier toutes les informations aupr\u00e8s de toutes les sources disponibles et cr\u00e9dibles ?\u00a0 Etre pr\u00e9sent sur le terrain malgr\u00e9 les risques de violence ?<\/p>\n<p>Il faut bien le souligner : pour des raisons de s\u00e9curit\u00e9, le personnel non essentiel a \u00e9t\u00e9 pri\u00e9 de rentrer \u00e0 la maison. Sur un effectif de 45 personnes tous services confondus, une dizaine de journalistes est rest\u00e9e pour assurer une \u00e9dition sp\u00e9ciale en deux langues, fran\u00e7ais et bambara, de 17H \u00e0 19H. L\u2019exp\u00e9rience des derni\u00e8res semaines a montr\u00e9 que lorsqu&rsquo;il y a une grosse manifestation, la capitale malienne est coup\u00e9e en deux. Difficile, voire impossible de se rendre d\u2019une rive \u00e0 l\u2019autre du Fleuve Djoliba qui coupe la ville en deux. Il faut donc anticiper sur ce blocage pr\u00e9visible mais les journalistes qui rentrent \u00e0 la maison doivent se rendre disponibles et contribuer \u00e0 la production d\u2019\u00e9l\u00e9ments \u00e0 distance \u00e0 la demande du r\u00e9dacteur en chef. Une le\u00e7on apprise des mesures de contingence prises contre la Covid-19. Toute la r\u00e9daction est \u00e9quip\u00e9e pour r\u00e9aliser une interview \u00e0 distance, \u00e9crire un texte, monter un son et l\u2019envoyer pour diffusion.<\/p>\n<p>Ce dispositif a d\u2019ailleurs \u00e9t\u00e9 fort utile pour la Matinale sp\u00e9ciale du lendemain 19 ao\u00fbt. C\u2019est ainsi que la r\u00e9daction a r\u00e9ussi \u00e0 traiter les \u00e9v\u00e9nements survenus dans la nuit, surtout la d\u00e9claration \u00e0 la t\u00e9l\u00e9vision du Pr\u00e9sident IBK annon\u00e7ant sa d\u00e9mission, et quelques heures plus tard la premi\u00e8re proclamation des officiers, confirmant le coup d\u2019\u00e9tat militaire.<\/p>\n<p>La r\u00e9activit\u00e9 de Studio Tamani ne s\u2019est pas limit\u00e9e aux programmes radiophoniques. La dimension 2.0 a \u00e9t\u00e9 prise en compte. Le site Web a fait l\u2019objet de mises \u00e0 jour r\u00e9guli\u00e8res. Des posts ont \u00e9t\u00e9 publi\u00e9s sur la page Facebook et des tweets sur le fil Twitter de Studio Tamani au fur et \u00e0 mesure que les informations \u00e9taient disponibles.<br \/>En fin de journ\u00e9e, le 18 ao\u00fbt, une appr\u00e9ciation venant d\u2019un internaute nous montrait que nous avions rempli notre mission : \u00ab Studio Tamani, l\u2019information impartiale en temps r\u00e9el\u00a0\u00bb.<\/p>\n<p><strong><em>Martin Faye, Repr\u00e9sentant de la Fondation Hirondelle au Mali<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s le Coup d&rsquo;\u00e9tat du 18 ao\u00fbt 2020 au Mali, la r\u00e9daction de Studio Tamani, le programme radio de la Fondation Hirondelle et de l&rsquo;URTEL au Mali, \u00e9value son action dans la couverture de ces \u00e9v\u00e9nements. Martin Faye, Repr\u00e9sentant de la Fondation Hirondelle au Mali, explique les d\u00e9fis et mesures prises pour permettre \u00e0 la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5245,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[173],"tags":[230,233,246],"class_list":["post-1255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","tag-operation-en-cours-mali","tag-expertise-construction-de-la-paix","tag-recherche-apprentissage"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:41:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/1255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=1255"}],"version-history":[{"count":0,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/1255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/5245"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=1255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=1255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=1255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}