{"id":14851,"date":"2024-12-10T08:44:22","date_gmt":"2024-12-10T07:44:22","guid":{"rendered":"https:\/\/www.hirondelle.org\/adapting-to-changing-information-needs"},"modified":"2025-01-13T11:06:46","modified_gmt":"2025-01-13T10:06:46","slug":"adapting-to-changing-information-needs","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/adapting-to-changing-information-needs","title":{"rendered":"S&rsquo;adapter \u00e0 l&rsquo;\u00e9volution des besoins d&rsquo;information"},"content":{"rendered":"<p><strong><span style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\">La derni\u00e8re campagne pr\u00e9sidentielle aux Etats-Unis a montr\u00e9 \u00e0 quel point le paysage m\u00e9diatique \u00e9volue, en fonction des nouveaux besoins des utilisateur\u00b7rice\u00b7s des m\u00e9dias. Comment le journalisme d\u2019information peut-il s\u2019adapter \u00e0 cette nouvelle donne, pour retrouver un large \u00e9cho au b\u00e9n\u00e9fice du public ?<\/span><\/strong><br style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\" \/><br style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\" \/><span style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\">Le 6 novembre dernier, le r\u00e9sultat de l\u2019\u00e9lection pr\u00e9sidentielle aux Etats-Unis a une fois de plus surpris la plupart des m\u00e9dias d\u2019information \u00e9tablis, et d\u00e9\u00e7u la plupart des partisan\u00b7e\u00b7s d\u2019un journalisme factuel, v\u00e9rifi\u00e9 et sourc\u00e9, r\u00e9pondant aux grandes chartes d\u00e9ontologiques du m\u00e9tier. Au terme d\u2019une campagne \u00e9lectorale qui s\u2019est jou\u00e9e davantage sur les r\u00e9seaux sociaux, les vid\u00e9os d\u2019influenceur\u00b7se\u00b7s et les plateformes de podcasts que sur les m\u00e9dias traditionnels, un candidat \u00ab anti-syst\u00e8me \u00bb a remport\u00e9 le suffrage populaire. Il a \u00e9t\u00e9 \u00e9lu en boudant la traditionnelle interview t\u00e9l\u00e9visuelle des candidat\u00b7e\u00b7s dans l\u2019\u00e9mission \u00ab 60 minutes \u00bb sur CBS, et en privil\u00e9giant sur les r\u00e9seaux sociaux une expression r\u00e9duite \u00e0 des textes de 280 signes ou \u00e0 des vid\u00e9os de 60 secondes. Plus qu\u2019en 2016 encore, Donald Trump a su comprendre et s\u2019adapter aux nouveaux besoins des utilisateurs des m\u00e9dias.<\/span><br style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\" \/><br style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\" \/><span style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\">Depuis le d\u00e9but des ann\u00e9es 2020 en effet, les r\u00e9seaux sociaux sont devenus les principales voies d\u2019acc\u00e8s \u00e0 l\u2019information en ligne, c\u2019est-\u00e0-dire les m\u00e9dias dominants dans les pays occidentaux et \u00e9mergents. Mais leurs utilisateur\u00b7rice\u00b7s y recherchent moins une information \u00e9quilibr\u00e9e qu\u2019une information qui leur ressemble : ils s\u2019orientent moins vers les contenus post\u00e9s par les m\u00e9dias traditionnels que vers des vid\u00e9os de personnalit\u00e9s qui leur plaisent, et qu\u2019ils peuvent rapidement partager avec leur communaut\u00e9. L\u2019information journalistique, pas toujours la plus agr\u00e9able \u00e0 consulter, reste une denr\u00e9e appr\u00e9ci\u00e9e car elle permet de conna\u00eetre et de comprendre le monde, surtout dans sa dimension locale et internationale. Mais elle est devenue un besoin mineur des utilisateur\u00b7rice\u00b7s de m\u00e9dias, \u00e9tourdi e\u00b7s par le grand flux des messages plus satisfaisants qui apparaissent chaque minute sur leurs \u00e9crans.<\/span><br style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\" \/><br style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\" \/><span style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\">Dans les zones de crises ou de conflits, o\u00f9 l\u2019acc\u00e8s \u00e0 une information fiable est un besoin souvent plus vital qu\u2019ailleurs, la situation n\u2019est pas tr\u00e8s diff\u00e9rente. Les personnes qui s\u2019y trouvent expriment trois principaux besoins m\u00e9diatiques : pouvoir communiquer avec leurs proches, avoir acc\u00e8s localement \u00e0 une information de confiance, et pouvoir s\u2019orienter dans le grand chaos informationnel ambiant, rendu encore plus illisible par les batailles que s\u2019y livrent \u00e9galement les bellig\u00e9rants. En mettant en regard ces diff\u00e9rentes situations, ce num\u00e9ro de M\u00e9diation propose d\u2019analyser les besoins des utilisateur\u00b7rice\u00b7s dans des espaces informationnels mouvants, afin de trouver des voies pour que l\u2019information journalistique puisse davantage leur parler. En vue de contribuer \u00e0 prot\u00e9ger des populations en danger, \u00e0 promouvoir la d\u00e9mocratie et \u00e0 partager un monde commun dans des soci\u00e9t\u00e9s qui ont plus que jamais besoin de lien.<\/span><\/p>\n<div style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\">\u00a0<\/div>\n<p><span style=\"color: #222222; font-family: Arial, Helvetica, sans-serif; font-size: small;\">Cet extrait est tir\u00e9 du 13\u00e8me num\u00e9ro du M\u00e9diation nomm\u00e9 \u00ab\u00a0S&rsquo;adapter \u00e0 l&rsquo;\u00e9volution des besoins d&rsquo;information\u00a0\u00bb, que vous trouverez attach\u00e9 en haut de cet article.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La derni\u00e8re campagne pr\u00e9sidentielle aux Etats-Unis a montr\u00e9 \u00e0 quel point le paysage m\u00e9diatique \u00e9volue, en fonction des nouveaux besoins des utilisateur\u00b7rice\u00b7s des m\u00e9dias. Comment le journalisme d\u2019information peut-il s\u2019adapter \u00e0 cette nouvelle donne, pour retrouver un large \u00e9cho au b\u00e9n\u00e9fice du public ?Le 6 novembre dernier, le r\u00e9sultat de l\u2019\u00e9lection pr\u00e9sidentielle aux Etats-Unis a [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":14952,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[171],"tags":[],"class_list":["post-14851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notre-actualite"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:36:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/14851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=14851"}],"version-history":[{"count":1,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/14851\/revisions"}],"predecessor-version":[{"id":14987,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/14851\/revisions\/14987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/14952"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=14851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=14851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=14851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}