{"id":1591,"date":"2021-12-14T13:07:36","date_gmt":"2021-12-14T12:07:36","guid":{"rendered":"https:\/\/www.hirondelle.org\/prendre-en-compte-les-voix-du-public-mediation-n-8-janvier-2022-2"},"modified":"2021-12-14T13:07:36","modified_gmt":"2021-12-14T12:07:36","slug":"prendre-en-compte-les-voix-du-public-mediation-n-8-janvier-2022-2","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/prendre-en-compte-les-voix-du-public-mediation-n-8-janvier-2022-2","title":{"rendered":"Prendre en compte les voix du public &#8211; MEDIATION N\u00b08, Janvier 2022"},"content":{"rendered":"<p>Confront\u00e9s \u00e0 une crise de confiance majeure depuis le d\u00e9but des ann\u00e9es 2010, les m\u00e9dias multiplient les initiatives pour tenter de renouer avec leur public. Jusqu\u2019\u00e0 leur donner un v\u00e9ritable r\u00f4le dans la production de l\u2019information.\u00a0A lire dans le huiti\u00e8me num\u00e9ro de notre publication semestrielle, \u00ab\u00a0M\u00e9diation\u00a0\u00bb, \u00e0 feuilleter ou t\u00e9l\u00e9charger ci-dessus, avec des interviews et t\u00e9moignages de journalistes et chercheurs, des chiffres et des cartes pour nourrir la r\u00e9flexion, et donner des pistes d&rsquo;action.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confront\u00e9s \u00e0 une crise de confiance majeure depuis le d\u00e9but des ann\u00e9es 2010, les m\u00e9dias multiplient les initiatives pour tenter de renouer avec leur public. Jusqu\u2019\u00e0 leur donner un v\u00e9ritable r\u00f4le dans la production de l\u2019information.\u00a0A lire dans le huiti\u00e8me num\u00e9ro de notre publication semestrielle, \u00ab\u00a0M\u00e9diation\u00a0\u00bb, \u00e0 feuilleter ou t\u00e9l\u00e9charger ci-dessus, avec des interviews et [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4237,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[168],"tags":[],"class_list":["post-1591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-presse"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:25:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/1591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=1591"}],"version-history":[{"count":0,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/1591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/4237"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=1591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=1591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=1591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}