{"id":18996,"date":"2025-05-25T22:27:00","date_gmt":"2025-05-25T20:27:00","guid":{"rendered":"https:\/\/www.hirondelle.org\/?p=18996"},"modified":"2025-05-30T15:30:35","modified_gmt":"2025-05-30T13:30:35","slug":"comment-les-radios-au-sahel-bousculent-les-stereotypes-de-genre","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/comment-les-radios-au-sahel-bousculent-les-stereotypes-de-genre","title":{"rendered":"Comment les radios au Sahel bousculent\u00a0les st\u00e9r\u00e9otypes de genre"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"477\" src=\"https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/05\/PhotoEmma-1-1024x477.png\" alt=\"\" class=\"wp-image-19007 size-full\" srcset=\"https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/05\/PhotoEmma-1-1024x477.png 1024w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/05\/PhotoEmma-1-300x140.png 300w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/05\/PhotoEmma-1-768x358.png 768w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/05\/PhotoEmma-1-1000x466.png 1000w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/05\/PhotoEmma-1.png 1233w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Dr Emma Heywood est ma\u00eetre de conf\u00e9rences en journalisme, radio et communication \u00e0 l\u2019Universit\u00e9 de Sheffield, et experte du r\u00f4le des m\u00e9dias dans les r\u00e9gions touch\u00e9es par les conflits. Ses recherches portent sur les m\u00e9dias et le genre en Afrique de l\u2019Ouest, o\u00f9 elle dirige plusieurs projets sur l\u2019influence de la radio dans l\u2019autonomisation des femmes et la perception des st\u00e9r\u00e9otypes de genre.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Quels st\u00e9r\u00e9otypes de genre les plus fr\u00e9quents avez-vous observ\u00e9s dans les radios locales au Sahel, et comment influencent-ils la perception des r\u00f4les sociaux ?<\/strong><br>Dans des contextes de conflit comme le Sahel, les r\u00f4les de genre traditionnels tendent \u00e0 se renforcer. Les hommes sont souvent repr\u00e9sent\u00e9s comme des protecteurs ou des agresseurs \u2013 ceux qui partent au front \u2013 tandis que les femmes sont cantonn\u00e9es \u00e0 un r\u00f4le de soutien domestique. Cela se refl\u00e8te dans les pratiques radiophoniques : les femmes journalistes doivent souvent lutter pour se faire entendre lors des conf\u00e9rences de r\u00e9daction, et il leur est rarement donn\u00e9 l\u2019opportunit\u00e9 de proposer leurs id\u00e9es. On leur confie en g\u00e9n\u00e9ral des sujets dits \u00ab\u202fsociaux\u202f\u00bb ou \u00ab\u202fde soci\u00e9t\u00e9\u202f\u00bb comme la famille, la sant\u00e9 ou le bien-\u00eatre, tandis que les hommes couvrent la politique, l\u2019\u00e9conomie ou le sport. Ironiquement, dans des zones en conflit, ces th\u00e9matiques dites \u00ab\u202fsociales\u202f\u00bb englobent souvent des r\u00e9alit\u00e9s extr\u00eamement dures comme les violences bas\u00e9es sur le genre \u2014 des enjeux qui r\u00e9sonnent profond\u00e9ment chez les femmes journalistes. Elles sont \u00e9galement moins sollicit\u00e9es pour les reportages de terrain, \u00e0 cause de pr\u00e9jug\u00e9s sur leurs intentions ou de restrictions li\u00e9es aux d\u00e9placements et \u00e0 l\u2019h\u00e9bergement. <br>Ces st\u00e9r\u00e9otypes influencent la mani\u00e8re dont les jeunes femmes per\u00e7oivent leur place dans la soci\u00e9t\u00e9 et dans les m\u00e9dias. Beaucoup tentent de r\u00e9sister \u00e0 ces r\u00f4les \u2013 souvent inspir\u00e9es par les r\u00e9seaux sociaux \u2013 mais se heurtent \u00e0 des obstacles : la pression des proches masculins, des employeurs, voire de leurs propres coll\u00e8gues, eux-m\u00eames impr\u00e9gn\u00e9s des m\u00eames normes. Quant aux jeunes hommes, la pression de devoir correspondre \u00e0 une masculinit\u00e9 id\u00e9alis\u00e9e peut provoquer frustration\u2026 voire, dans certains cas, des violences domestiques en r\u00e9action \u00e0 une perte de rep\u00e8res.<\/p>\n\n\n\n<p><strong>Avez-vous observ\u00e9 des cas o\u00f9 la radio r\u00e9ussit \u00e0 d\u00e9construire ces st\u00e9r\u00e9otypes et \u00e0 promouvoir une image plus \u00e9quilibr\u00e9e ?<\/strong><br>Oui, certains exemples sont tr\u00e8s inspirants. Il existe des portraits marquants de femmes dans des r\u00f4les non traditionnels. Une \u00e9mission de <em>Studio Yafa<\/em> (Burkina Faso) a, par exemple, mis en lumi\u00e8re une m\u00e9canicienne \u2013 ce type de contenu est crucial, surtout quand il pr\u00e9sente des femmes locales auxquelles les auditrices et auditeurs peuvent s\u2019identifier. Quand le public entend parler d\u2019une femme d\u2019une ville voisine devenue \u00e9lue locale ou cheffe d\u2019entreprise, cela peut changer les repr\u00e9sentations et cr\u00e9er des d\u00e9clics. Certaines \u00e9missions cr\u00e9\u00e9es par des femmes et destin\u00e9es aux femmes ont \u00e9galement un fort impact. Et bien que ciblant un public f\u00e9minin, ces programmes sont aussi \u00e9cout\u00e9s par des hommes \u2014 ce qui est essentiel, car ils sont souvent les d\u00e9cideurs. Ces plateformes permettent aux femmes de gagner en confiance, de travailler en \u00e9quipe et de faire entendre leur voix sans avoir besoin d\u2019une validation masculine.<\/p>\n\n\n\n<p><strong>Quelles strat\u00e9gies les m\u00e9dias peuvent-ils adopter pour soutenir l\u2019\u00e9galit\u00e9 de genre dans des contextes fragiles comme le Sahel ?<\/strong><br>D\u2019abord, une prise de conscience chez les responsables de r\u00e9daction est essentielle \u2014 beaucoup ne r\u00e9alisent pas les d\u00e9fis suppl\u00e9mentaires auxquels les femmes sont confront\u00e9es. Il faut \u00e9galement revoir les politiques de recrutement. De nombreuses stations de radio exigent des dipl\u00f4mes que beaucoup de femmes n\u2019ont pas, \u00e0 cause d\u2019in\u00e9galit\u00e9s syst\u00e9miques, les excluant d\u2019embl\u00e9e. De fait, valoriser le potentiel plut\u00f4t que les seules qualifications acad\u00e9miques et offrir des formations continues sur le terrain seraient de r\u00e9els leviers. Il est aussi crucial d\u2019am\u00e9nager le travail. Les responsabilit\u00e9s domestiques p\u00e8sent plus lourdement sur les femmes, et des pr\u00e9suppos\u00e9s sur leur disponibilit\u00e9 limitent leurs chances d\u2019\u00eatre envoy\u00e9es en reportage. Des r\u00e9dacteurs en chef doivent parfois n\u00e9gocier avec les maris pour qu\u2019elles puissent travailler tard ou voyager. Les femmes ne devraient pas \u00eatre p\u00e9nalis\u00e9es parce qu\u2019elles sont mari\u00e9es ou m\u00e8res.<br>Enfin, il est indispensable qu\u2019elles aient acc\u00e8s \u00e0 tous les types de reportages \u2013 politique, \u00e9conomie, conflits \u2013 et pas seulement aux sujets dits \u00ab f\u00e9minins \u00bb. Cela les valorise professionnellement et habitue aussi le public \u00e0 entendre des femmes s\u2019exprimer sur tous les enjeux. Changer les attentes du public est un processus de longue haleine \u2014 mais avec les m\u00e9dias, cela se fait progressivement, goutte apr\u00e8s goutte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dr Emma Heywood est ma\u00eetre de conf\u00e9rences en journalisme, radio et communication \u00e0 l\u2019Universit\u00e9 de Sheffield, et experte du r\u00f4le des m\u00e9dias dans les r\u00e9gions touch\u00e9es par les conflits. Ses recherches portent sur les m\u00e9dias et le genre en Afrique de l\u2019Ouest, o\u00f9 elle dirige plusieurs projets sur l\u2019influence de la radio dans l\u2019autonomisation des [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":19226,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,171],"tags":[],"class_list":["post-18996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","category-notre-actualite"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:59:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/18996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=18996"}],"version-history":[{"count":8,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/18996\/revisions"}],"predecessor-version":[{"id":19234,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/18996\/revisions\/19234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/19226"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=18996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=18996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=18996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}