{"id":1961,"date":"2023-06-20T11:49:43","date_gmt":"2023-06-20T09:49:43","guid":{"rendered":"https:\/\/www.hirondelle.org\/audit-des-comptes-2022"},"modified":"2023-06-20T11:49:43","modified_gmt":"2023-06-20T09:49:43","slug":"audit-des-comptes-2022","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/audit-des-comptes-2022","title":{"rendered":"Audit des comptes 2022"},"content":{"rendered":"<p>En cliquant sur le lien ci-dessus, t\u00e9l\u00e9chargez l&rsquo;audit des comptes annuels 2022 de la Fondation Hirondelle, r\u00e9alis\u00e9 par PricewaterhouseCoopers SA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cliquant sur le lien ci-dessus, t\u00e9l\u00e9chargez l&rsquo;audit des comptes annuels 2022 de la Fondation Hirondelle, r\u00e9alis\u00e9 par PricewaterhouseCoopers SA.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[157],"tags":[],"class_list":["post-1961","post","type-post","status-publish","format-standard","hentry","category-audit-des-comptes"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:14:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/1961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=1961"}],"version-history":[{"count":0,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/1961\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=1961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=1961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=1961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}