{"id":19765,"date":"2025-07-06T20:30:00","date_gmt":"2025-07-06T18:30:00","guid":{"rendered":"https:\/\/www.hirondelle.org\/?p=19765"},"modified":"2025-07-07T10:28:10","modified_gmt":"2025-07-07T08:28:10","slug":"linformation-fiable-remede-a-la-desinformation","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/linformation-fiable-remede-a-la-desinformation","title":{"rendered":"L&rsquo;information fiable, rem\u00e8de \u00e0 la d\u00e9sinformation"},"content":{"rendered":"\n<p>Dans un espace m\u00e9diatique domin\u00e9 par les r\u00e9seaux sociaux, la d\u00e9sinformation a trouv\u00e9 un terreau fertile pour prolif\u00e9rer ces dix derni\u00e8res ann\u00e9es. Pour contrer ce ph\u00e9nom\u00e8ne nuisible \u00e0 la coh\u00e9sion des soci\u00e9t\u00e9s, une approche pr\u00e9ventive reste \u00e0 inventer.<\/p>\n\n\n\n<p>En 2025, dans l\u2019espace m\u00e9diatique en ligne, la d\u00e9sinformation est devenue un ph\u00e9nom\u00e8ne \u00e0 la fois g\u00e9n\u00e9ralis\u00e9, lucratif et efficace. Plus de 17 % du trafic mondial sur Internet est factice, constitu\u00e9 de robots, d\u2019utilisateurs insinc\u00e8res ou malveillants. Pr\u00e8s de la moiti\u00e9 de la population mondiale d\u00e9clare s\u2019\u00eatre laiss\u00e9e berner par une infox au cours de l\u2019ann\u00e9e \u00e9coul\u00e9e. Plus de 2,6 milliards de dollars US sont achet\u00e9s en espaces publicitaires sur des sites de d\u00e9sinformation. Et 87 % de la population mondiale estime que la d\u00e9sinformation a d\u00e9j\u00e0 eu un impact important sur la vie politique de son pays.<\/p>\n\n\n\n<p>Comme l\u2019a montr\u00e9 l\u2019histoire du XXe si\u00e8cle, la d\u00e9sinformation de masse ne date pas d\u2019hier. Elle a longtemps \u00e9t\u00e9 l\u2019apanage de r\u00e9gimes autoritaires, qui faisaient \u0153uvre de propagande m\u00e9diatique quand les r\u00e9gimes d\u00e9mocratiques favorisaient au contraire un pluralisme des m\u00e9dias garantissant \u00e0 la fois la libert\u00e9 d\u2019expression et le contr\u00f4le des puissants par un public inform\u00e9.<\/p>\n\n\n\n<p>Mais depuis dix ans, la domination des r\u00e9seaux sociaux dans le paysage m\u00e9diatique mondial a permis \u00e0 la d\u00e9sinformation de prendre des formes multiples et de prolif\u00e9rer : infox destin\u00e9es \u00e0 susciter l\u2019inqui\u00e9tude chez certains profils psychologiques cibl\u00e9s (Cambridge Analytica), chaos informationnel propag\u00e9 par des acteurs m\u00e9diatico-militaires pour jeter un \u00e9cran de fum\u00e9e sur leurs activit\u00e9s (groupe Concord de feu Evgueny Prigojine), industrie du deep fake dop\u00e9e \u00e0 l\u2019intelligence artificielle pour mener des campagnes d\u2019influence politique dans des pays \u00e9trangers (Doppelg\u00e4nger)\u2026 Avec \u00e0 chaque fois, la d\u00e9multiplication de ces campagnes par des utilisateur.rice.s conditionn\u00e9.e.s par des algorithmes, et prompts \u00e0 partager ces contenus inqui\u00e9tants \u00e0 la multitude de leurs contacts d\u2019affinit\u00e9.<\/p>\n\n\n\n<p>Face \u00e0 cette tra\u00een\u00e9e de poudre d\u00e9sinformationnelle, les vieux rem\u00e8des ont fait long feu : le fact-checking a posteriori, s\u2019il reste utile, est toujours s\u00fbr d\u2019avoir trois longueurs de retard. Une approche pr\u00e9ventive reste \u00e0 inventer, et elle passe par trois niveaux de responsabilit\u00e9s : celle des m\u00e9dias qui doivent produire et diffuser plus d\u2019information de qualit\u00e9, celle des \u00c9tats qui doivent favoriser la circulation de l\u2019information fiable en encourageant le journalisme et en r\u00e9gulant les plateformes pour lui donner plus de visibilit\u00e9, et celle du public \u00e0 qui il appartient par ses choix de consommation m\u00e9diatique et son esprit critique de ne pas se laisser tromper.<\/p>\n\n\n\n<p>En partant des exp\u00e9riences de la Fondation Hirondelle, ce num\u00e9ro de <em>M\u00e9diation<\/em> propose un tour d\u2019horizon de quelques initiatives en la mati\u00e8re, habit\u00e9es par la conviction qu\u2019une soci\u00e9t\u00e9 mieux inform\u00e9e est aussi mieux outill\u00e9e pour aborder les grands probl\u00e8mes auxquels elle est confront\u00e9e, de fa\u00e7on inclusive et concert\u00e9e.<\/p>\n\n\n\n<p><em>Cet extrait est tir\u00e9 du 15\u00e8me num\u00e9ro du M\u00e9diation \u00ab&nbsp;L&rsquo;information fiable, rem\u00e8de \u00e0 la d\u00e9sinformation&nbsp;\u00bb, que vous trouverez attach\u00e9 en haut de cet article<\/em> <em><a href=\"https:\/\/www.hirondelle.org\/fr\/linformation-fiable-remede-a-la-desinformation-mediation-n15-juillet-2025\">ou ici<\/a><\/em>.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un espace m\u00e9diatique domin\u00e9 par les r\u00e9seaux sociaux, la d\u00e9sinformation a trouv\u00e9 un terreau fertile pour prolif\u00e9rer ces dix derni\u00e8res ann\u00e9es. Pour contrer ce ph\u00e9nom\u00e8ne nuisible \u00e0 la coh\u00e9sion des soci\u00e9t\u00e9s, une approche pr\u00e9ventive reste \u00e0 inventer. En 2025, dans l\u2019espace m\u00e9diatique en ligne, la d\u00e9sinformation est devenue un ph\u00e9nom\u00e8ne \u00e0 la fois g\u00e9n\u00e9ralis\u00e9, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":19926,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[171],"tags":[],"class_list":["post-19765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notre-actualite"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:59:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/19765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=19765"}],"version-history":[{"count":5,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/19765\/revisions"}],"predecessor-version":[{"id":19939,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/19765\/revisions\/19939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/19926"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=19765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=19765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=19765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}