{"id":21780,"date":"2025-12-17T11:00:00","date_gmt":"2025-12-17T10:00:00","guid":{"rendered":"https:\/\/www.hirondelle.org\/?p=21780"},"modified":"2026-01-06T14:56:14","modified_gmt":"2026-01-06T13:56:14","slug":"lia-un-changement-radical-dans-lecosysteme-dinformations","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/lia-un-changement-radical-dans-lecosysteme-dinformations","title":{"rendered":"L\u2019IA, un changement radical dans l&rsquo;\u00e9cosyst\u00e8me d&rsquo;informations"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:19% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"364\" height=\"234\" src=\"https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/12\/image.png\" alt=\"\" class=\"wp-image-21781 size-full\" srcset=\"https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/12\/image.png 364w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/12\/image-300x193.png 300w\" sizes=\"auto, (max-width: 364px) 100vw, 364px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Urvashi Aneja<\/strong> dirige \u00e0 Goa le <strong><a href=\"https:\/\/www.digitalfutureslab.in\/\">Digital Futures Lab<\/a><\/strong>, groupe de r\u00e9flexion travaillant \u00e0 un \u00ab avenir o\u00f9 la technologie est au service de tou.te.s, et non d&rsquo;une minorit\u00e9 \u00bb. Elle explique comment l&rsquo;IA transforme la diffusion de l&rsquo;information en Inde, soulignant son potentiel et ses \u00e9cueils.<\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Les chiffres montrent que l\u2019acc\u00e8s aux actualit\u00e9s via l&rsquo;IA suscitent un vif int\u00e9r\u00eat en Inde. Quelles opportunit\u00e9s l&rsquo;IA offre-t-elle pour la diffusion de l&rsquo;information dans ce pays ?<\/strong><\/p>\n\n\n\n<p><strong>Urvashi Aneja<\/strong> : Elle offre une opportunit\u00e9 consid\u00e9rable sur la diversit\u00e9 linguistique. Ces outils permettent aux personnes qui ne parlent pas les langues dominantes d&rsquo;acc\u00e9der \u00e0 l&rsquo;actualit\u00e9 dans leur langue locale, ce qui est tr\u00e8s important car l&rsquo;Inde compte plus de 200 langues. N\u00e9anmoins, ces outils sont encore loin d\u2019\u00eatre performants dans toutes ces langues. Un autre aspect concerne l&rsquo;alphab\u00e9tisation : une grande partie de la population indienne est peu alphab\u00e9tis\u00e9e. Le fait que ces outils soient d\u00e9sormais accessibles dans des formats multim\u00e9dias offre de nouvelles possibilit\u00e9s aux personnes qui veulent interagir avec l&rsquo;information, m\u00eame si elles ne sont pas tr\u00e8s alphab\u00e9tis\u00e9es. Elles peuvent ainsi \u00eatre auditrices ou spectatrices, mais aussi productrices de contenus d&rsquo;information sous diff\u00e9rents formats. Troisi\u00e8mement, l&rsquo;IA r\u00e9duit les co\u00fbts de production de l&rsquo;information. Il n&rsquo;est plus n\u00e9cessaire de disposer d&rsquo;un grand studio ou d&rsquo;une grande \u00e9quipe. Une seule personne peut filmer un reportage, enregistrer des interviews, les monter et les publier. Bien s\u00fbr, il \u00e9tait d\u00e9j\u00e0 possible avant l&rsquo;IA de produire une vid\u00e9o seul.e et de la diffuser sur une plateforme. Mais l&rsquo;IA a rendu ces actions beaucoup plus faciles pour les particuliers ou les tr\u00e8s petits m\u00e9dias. Et la baisse des co\u00fbts de production signifie que beaucoup plus de voix, de r\u00e9gions g\u00e9ographiques et de points de vue ont la possibilit\u00e9 d\u2019\u00eatre repr\u00e9sent\u00e9s, ce qui n&rsquo;est pas le cas lorsque l&rsquo;industrie de l&rsquo;information est plus monolithique et centralis\u00e9e.<\/p>\n\n\n\n<p><strong>Quels sont les principaux risques li\u00e9s \u00e0 l\u2019utilisation de l&rsquo;IA dans l&rsquo;information ?<\/strong><\/p>\n\n\n\n<p>Le principal risque concerne la d\u00e9sinformation et les fausses informations, avec la facilit\u00e9 croissante de cr\u00e9er des contenus trompeurs. Le probl\u00e8me est que bon nombre des outils techniques mis en place pour authentifier les contenus, tels que les filigranes ou les tatouages num\u00e9riques, s&rsquo;av\u00e8rent vite inop\u00e9rants. Il est donc difficile d\u2019aider les gens \u00e0 distinguer le vrai du faux. En outre, la qualit\u00e9 des informations produites par les organes de presse traditionnels a baiss\u00e9, pour diverses raisons, notamment parce que leurs revenus publicitaires sont d\u00e9cim\u00e9s par les r\u00e9seaux sociaux et d\u00e9sormais plus encore par l&rsquo;IA g\u00e9n\u00e9rative. Aujourd&rsquo;hui, la plupart des jeunes en Inde ne lisent plus les journaux et ne consultent m\u00eame plus les sites d&rsquo;information. Beaucoup se contentent de lire les r\u00e9sultats g\u00e9n\u00e9r\u00e9s par l&rsquo;IA. Or, la fiabilit\u00e9 de ces r\u00e9sultats est de plus en plus faible. Si nous ne r\u00e9solvons pas ce probl\u00e8me, les \u00c9tats pourraient adopter des r\u00e9glementations tr\u00e8s strictes qui pourraient avoir un impact n\u00e9gatif sur la libert\u00e9 d&rsquo;expression, ou encore laisser les plateformes de r\u00e9seaux sociaux devenir les arbitres charg\u00e9s de v\u00e9rifier l&rsquo;exactitude des informations. [&#8230;]<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>Cet extrait est tir\u00e9 du 16\u00e8me num\u00e9ro du M\u00e9diation \u00ab\u00a0L&rsquo;information face au d\u00e9fi de l&rsquo;intelligence artificielle \u00bb, que vous trouverez attach\u00e9 en haut de cet article <a href=\"https:\/\/www.hirondelle.org\/wp-content\/uploads\/2025\/12\/FH_MEDIATION_N%C2%B016_FRA_V4_web_PP.pdf\">ou ici.<\/a><\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Urvashi Aneja dirige \u00e0 Goa le Digital Futures Lab, groupe de r\u00e9flexion travaillant \u00e0 un \u00ab avenir o\u00f9 la technologie est au service de tou.te.s, et non d&rsquo;une minorit\u00e9 \u00bb. Elle explique comment l&rsquo;IA transforme la diffusion de l&rsquo;information en Inde, soulignant son potentiel et ses \u00e9cueils. Les chiffres montrent que l\u2019acc\u00e8s aux actualit\u00e9s via [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":21792,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[171,147],"tags":[259,460],"class_list":["post-21780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notre-actualite","category-actualites-de-la-fondation-hirondelle","tag-expertise-ecosystemes-mediatiques","tag-expertise-me-desinformation"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:14:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/21780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=21780"}],"version-history":[{"count":9,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/21780\/revisions"}],"predecessor-version":[{"id":27711,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/21780\/revisions\/27711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/21792"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=21780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=21780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=21780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}