{"id":25312,"date":"2026-04-15T14:43:05","date_gmt":"2026-04-15T12:43:05","guid":{"rendered":"https:\/\/www.hirondelle.org\/?p=25312"},"modified":"2026-04-15T14:43:07","modified_gmt":"2026-04-15T12:43:07","slug":"un-test-grandeur-nature-radio-ndeke-luka-au-defi-du-quadruple-scrutin-centrafricain","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/un-test-grandeur-nature-radio-ndeke-luka-au-defi-du-quadruple-scrutin-centrafricain","title":{"rendered":"\u00ab Un test grandeur nature \u00bb : Radio Ndeke Luka au d\u00e9fi du quadruple scrutin centrafricain"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size\"><em>Photo : un journaliste de Radio Ndeke Luka couvre la c\u00e9r\u00e9monie d&rsquo;investiture du pr\u00e9sident de la R\u00e9publique \u00e0 Bangui, le 30 mars 2026.<em>\u00a9<\/em> Radio Ndeke Luka <\/em><\/p>\n\n\n\n<p>En d\u00e9cembre 2025, la R\u00e9publique centrafricaine a organis\u00e9 un quadruple scrutin \u2014 pr\u00e9sidentielle, l\u00e9gislatives, r\u00e9gionales et municipales \u2014 une premi\u00e8re depuis pr\u00e8s de 40 ans. <strong>Pendant plus de trois mois, Radio Ndeke Luka (RNL) a suivi ce processus de bout en bout<\/strong>, <a href=\"https:\/\/www.radiondekeluka.org\/elections\">du lancement de la campagne le 16 d\u00e9cembre jusqu&rsquo;\u00e0 l&rsquo;investiture du pr\u00e9sident le 30 mars \u00e0 Bangui<\/a>. <\/p>\n\n\n\n<p><strong>Brice Landry Ndangui,<\/strong> r\u00e9dacteur en chef de RNL, dresse un bilan de cette couverture.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em><strong>Comment Radio Ndeke Luka s\u2019est-elle pr\u00e9par\u00e9e \u00e0 couvrir ces \u00e9lections, et quel bilan de cette couverture m\u00e9diatique tirez-vous aujourd\u2019hui apr\u00e8s l\u2019investiture du 30 mars ?<\/strong><\/em><\/p>\n\n\n\n<p>Radio Ndeke Luka n\u2019a pas attendu la convocation du corps \u00e9lectoral pour se pr\u00e9parer \u00e0 la couverture du processus \u00e9lectoral dont le second tour est pr\u00e9vu fin avril. La pr\u00e9paration a commenc\u00e9 d\u00e8s l\u2019adoption du chronogramme avec un plan de couverture en trois \u00e9tapes\u00a0: <strong>la p\u00e9riode pr\u00e9-\u00e9lectorale, la p\u00e9riode de campagne \u00e9lectorale jusqu\u2019au vote et la p\u00e9riode post-\u00e9lectorale<\/strong>. Toutes nos \u00e9quipes (r\u00e9daction, programmes, technique et cellule de fact-checking) ont \u00e9t\u00e9 mobilis\u00e9es pour ce travail.<\/p>\n\n\n\n<p>Concernant la p\u00e9riode pr\u00e9-\u00e9lectorale, <strong>nous avons mis en place des sensibilisations \u00e0 l\u2019antenne sur les diff\u00e9rentes \u00e9tapes<\/strong>, notamment la publication de la cartographie \u00e9lectorale, le recensement des \u00e9lecteurs, l\u2019importance de la participation des jeunes, des femmes, des minorit\u00e9s, etc. <strong>Nous avons aussi mis un accent particulier sur l\u2019\u00e9ducation aux m\u00e9dias et la lutte contre la d\u00e9sinformation<\/strong>. Nous avons re\u00e7u beaucoup de retours positifs des auditeurs et de certains partenaires.<\/p>\n\n\n\n<p>Durant la p\u00e9riode de campagne, nous avons propos\u00e9 <strong>une couverture impartiale et ind\u00e9pendante en donnant la parole de mani\u00e8re \u00e9quilibr\u00e9e et \u00e9quitable \u00e0 tous les candidats \u00e0 la pr\u00e9sidentielle.<\/strong> Ceci, gr\u00e2ce \u00e0 un dispositif interne d\u00e9ploy\u00e9 pour cette op\u00e9ration, particuli\u00e8rement l\u2019\u00e9laboration d\u2019une grille sp\u00e9ciale et d\u2019une charte couvrant toute la p\u00e9riode de la campagne jusqu\u2019au jour du vote.<\/p>\n\n\n\n<p>La derni\u00e8re \u00e9tape consiste en la publication des r\u00e9sultats provisoires par l\u2019Autorit\u00e9 nationale des \u00e9lections et des r\u00e9sultats d\u00e9finitifs par le Conseil constitutionnel. Aujourd\u2019hui, le premier tour est compl\u00e8tement boucl\u00e9 avec l\u2019\u00e9lection du pr\u00e9sident et son investiture ce 30 mars \u00e0 Bangui.<\/p>\n\n\n\n<p>En ce qui nous concerne, le bilan est positif malgr\u00e9 les nombreux d\u00e9fis auxquels RNL et les m\u00e9dias de mani\u00e8re g\u00e9n\u00e9rale \u00e9taient confront\u00e9s.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em><strong>Pourquoi est-il important qu\u2019un m\u00e9dia ind\u00e9pendant couvre les \u00e9lections dans le contexte de la RCA&nbsp;? Et quels \u00e9taient les principaux enjeux \u00e0 couvrir&nbsp;?<\/strong><\/em><\/p>\n\n\n\n<p>La RCA a travers\u00e9 pr\u00e8s d\u2019une d\u00e9cennie de graves crises politiques, militaires et humanitaires. Des \u00e9lections cr\u00e9dibles sont le fondement de la l\u00e9gitimit\u00e9 de l\u2019\u00c9tat, du sommet \u00e0 la base. Les \u00e9lections repr\u00e9sentent l\u2019un des socles de la d\u00e9mocratie, du dialogue et de la paix. Les citoyens ont besoin des m\u00e9dias qui donnent des informations fiables et cr\u00e9dibles, qui rencontrent leurs attentes. <strong>Pour y r\u00e9pondre, il faut un m\u00e9dia ind\u00e9pendant, impartial et cr\u00e9dible<\/strong>. C\u2019est le r\u00f4le que Radio Ndeke Luka et la Fondation Hirondelle jouent en RCA. La neutralit\u00e9 de la radio et de ses journalistes a contribu\u00e9 \u00e0 renforcer la confiance du public dans les m\u00e9dias \u00e0 travers le pays.<\/p>\n\n\n\n<p>Il faut reconna\u00eetre que RNL a fait face pour la premi\u00e8re fois \u00e0 une op\u00e9ration aussi complexe et d\u00e9licate\u00a0: <strong>ce quadruple scrutin a \u00e9t\u00e9 un test grandeur nature pour les ann\u00e9es \u00e0 venir.<\/strong> C\u2019est une premi\u00e8re depuis pr\u00e8s de 40 ans que la RCA a organis\u00e9 des \u00e9lections group\u00e9es de ce type.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em><strong>Comment RNL a-t-elle organis\u00e9 la couverture pour garantir l\u2019impartialit\u00e9 et donner la parole \u00e0 tous les candidats ?<\/strong><\/em><\/p>\n\n\n\n<p>Nous avons mis en place un dispositif qui a permis de rester professionnel et impartial. Ce dispositif comprend une grille sp\u00e9ciale \u00e9lection, la mise en place d\u2019une charte \u00e9lectorale et des dispositions techniques adapt\u00e9es.<\/p>\n\n\n\n<p>Ce dispositif, valid\u00e9 par le Haut Conseil de la Communication, a \u00e9t\u00e9 pr\u00e9sent\u00e9 aux candidats, \u00e0 leurs repr\u00e9sentants, aux partis politiques ainsi qu\u2019\u00e0 la soci\u00e9t\u00e9 civile et aux organisations professionnelles des m\u00e9dias. Chaque entit\u00e9 a re\u00e7u un exemplaire de notre Charte \u00e9lectorale. <strong>Toutes les \u00e9quipes de RNL ont \u00e9t\u00e9 sensibilis\u00e9es sur l\u2019importance du dispositif et sur la n\u00e9cessit\u00e9 de respecter les consignes donn\u00e9es<\/strong>.<\/p>\n\n\n\n<p>Ainsi,<strong> tous les candidats sont pass\u00e9s dans nos diff\u00e9rents programmes \u00e0 l\u2019antenne et sur nos supports num\u00e9riques<\/strong>. Pour la premi\u00e8re fois depuis son accession \u00e0 la magistrature supr\u00eame de l\u2019Etat en R\u00e9publique centrafricaine, le pr\u00e9sident Faustin Archange Touadera s\u2019est pr\u00eat\u00e9 \u00e0 cet exercice comme les autres candidats. Il s\u2018est rendu \u00e0 deux reprises \u00e0 la radio o\u00f9 il a pass\u00e9 plus de 3 heures pour le premier passage.<\/p>\n\n\n\n<p>Pour les l\u00e9gislatives, municipales et r\u00e9gionales, il \u00e9tait impossible d&rsquo;accorder un temps d&rsquo;antenne individuel \u00e0 des milliers de candidat\u00b7es. Nous avons donc assur\u00e9 une couverture globale, sur chaque localit\u00e9, <strong>gr\u00e2ce \u00e0 l\u2019appui de nos correspondants en r\u00e9gion et des \u00e9quipes \u00e0 Bangui.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.hirondelle.org\/wp-content\/uploads\/2026\/04\/ANE-1-1024x577.jpg\" alt=\"\" class=\"wp-image-25320\" style=\"aspect-ratio:1.7747899159663865;width:720px;height:auto\" srcset=\"https:\/\/www.hirondelle.org\/wp-content\/uploads\/2026\/04\/ANE-1-1024x577.jpg 1024w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2026\/04\/ANE-1-300x169.jpg 300w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2026\/04\/ANE-1-768x432.jpg 768w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2026\/04\/ANE-1-1536x865.jpg 1536w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2026\/04\/ANE-1-1000x563.jpg 1000w, https:\/\/www.hirondelle.org\/wp-content\/uploads\/2026\/04\/ANE-1.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Des agents de l&rsquo;Autorit\u00e9 nationale des \u00e9lections dans un bureau de vote \u00e0 Bangui, le 28 d\u00e9cembre 2025. Photo : Radio Ndeke Luka<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"has-medium-font-size\"><em><strong>Quelles mesures ont \u00e9t\u00e9 mises en place pour garantir l\u2019ind\u00e9pendance des journalistes ? Quels d\u00e9fis avez-vous rencontr\u00e9s sur ce plan ?<\/strong><\/em><\/p>\n\n\n\n<p>Tous les journalistes et correspondants ont \u00e9t\u00e9 form\u00e9s sur la couverture des \u00e9lections avec un accent sur la lutte contre la d\u00e9sinformation et l\u2019\u00e9ducation aux m\u00e9dias. <strong>Plusieurs s\u00e9ances d\u2019\u00e9changes et de sensibilisation ont eu lieu sur la charte \u00e9lectorale et le Code \u00e9thique et d\u00e9ontologique de la Fondation Hirondelle<\/strong> de mani\u00e8re \u00e0 garantir une couverture neutre, transparente et professionnelle.<\/p>\n\n\n\n<p>Le principal d\u00e9fi est venu du respect de ces consignes par les candidats, leurs repr\u00e9sentants ou leurs formations politiques. Certains tentaient d\u2019imposer leur volont\u00e9 ou de nous dicter la conduite \u00e0 tenir, ce qu\u2019ils n\u2019ont jamais eu l\u2019occasion de faire gr\u00e2ce au travail rigoureux de nos \u00e9quipes.<\/p>\n\n\n\n<p><strong>L&rsquo;autre d\u00e9fi \u00e9tait celui des ressources humaines, limit\u00e9es face \u00e0 l&rsquo;ampleur d&rsquo;une telle couverture<\/strong>. C\u2019est pourquoi la r\u00e9daction s\u2019est\u00a0focalis\u00e9e sur des sujets jug\u00e9s importants, par rapport \u00e0 leur int\u00e9r\u00eat pour le public.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em><strong>Durant la campagne, les scrutins, puis la retransmission en direct de l\u2019investiture, combien de journalistes ont \u00e9t\u00e9 mobilis\u00e9s et quels ont \u00e9t\u00e9 les principaux d\u00e9fis techniques ?<\/strong><\/em><\/p>\n\n\n\n<p>Au total, une cinquantaine de journalistes et technicien\u00b7nes \u00e0 Bangui, et plus d&rsquo;une quarantaine de correspondant\u00b7es \u00e0 travers le pays ont \u00e9t\u00e9 mobilis\u00e9\u00b7es pour la campagne et le jour du vote. Pour la c\u00e9r\u00e9monie d\u2019investiture, 10 journalistes et technicien\u00b7nes ont assur\u00e9 le direct depuis le stade, en plus d\u2019une forte \u00e9quipe mobilis\u00e9e \u00e0 l\u2019antenne et dans la capitale pour des reportages.<\/p>\n\n\n\n<p><strong>Les principaux d\u00e9fis ont r\u00e9sid\u00e9 dans la tenue du direct \u00e0 l\u2019antenne<\/strong> tout en assurant le bon fonctionnement du dispositif initialement pr\u00e9vu. Le jour du vote, nous avons eu des retours formidables sur le dispositif technique. En revanche, pendant la c\u00e9r\u00e9monie d\u2019investiture, quelques probl\u00e8mes intermittents ont marqu\u00e9 la diffusion du direct. Cela s\u2019explique d\u2019une part par les mesures s\u00e9curitaires contraignantes sur les lieux de la c\u00e9r\u00e9monie et d\u2019autre part par une panne qui a affect\u00e9 nos installations dans la matin\u00e9e de l\u2019\u00e9v\u00e8nement.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em><strong>Avez-vous eu des retours de la part des auditeur\u00b7ices \u00e9lecteur<em><strong>\u00b7<\/strong><\/em>ices sur le r\u00f4le de RNL dans leur compr\u00e9hension des enjeux des scrutins ?<\/strong><\/em><\/p>\n\n\n\n<p>Nous avons eu des retours positifs allant dans ce sens, non seulement de la part des auditeur\u00b7ices \u00e0 travers le pays mais aussi de certains de nos partenaires. Un sondage est actuellement en cours dans le but d\u2019avoir des donn\u00e9es document\u00e9es. Nous aurons l&rsquo;occasion d&rsquo;en partager les r\u00e9sultats le moment venu.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Pour continuer \u00e0 suivre les \u00e9lections en RCA, <a href=\"https:\/\/www.radiondekeluka.org\/elections\">rendez-vous sur Radio Ndeke Luka<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Photo : un journaliste de Radio Ndeke Luka couvre la c\u00e9r\u00e9monie d&rsquo;investiture du pr\u00e9sident de la R\u00e9publique \u00e0 Bangui, le 30 mars 2026.\u00a9 Radio Ndeke Luka En d\u00e9cembre 2025, la R\u00e9publique centrafricaine a organis\u00e9 un quadruple scrutin \u2014 pr\u00e9sidentielle, l\u00e9gislatives, r\u00e9gionales et municipales \u2014 une premi\u00e8re depuis pr\u00e8s de 40 ans. Pendant plus de trois [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":25313,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,171],"tags":[384],"class_list":["post-25312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","category-notre-actualite","tag-expertise-gouvernance-et-processus-democratique"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:26:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/25312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=25312"}],"version-history":[{"count":7,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/25312\/revisions"}],"predecessor-version":[{"id":25328,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/25312\/revisions\/25328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/25313"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=25312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=25312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=25312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}