{"id":360,"date":"2018-03-01T11:39:55","date_gmt":"2018-03-01T10:39:55","guid":{"rendered":"https:\/\/www.hirondelle.org\/projection-de-documentaires-sur-les-droits-humains-au-pakistan-et-en-afghanistan"},"modified":"2018-03-01T11:39:55","modified_gmt":"2018-03-01T10:39:55","slug":"projection-de-documentaires-sur-les-droits-humains-au-pakistan-et-en-afghanistan","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/projection-de-documentaires-sur-les-droits-humains-au-pakistan-et-en-afghanistan","title":{"rendered":"Droits Humains au Pakistan : trois documentaires diffus\u00e9s au FIFDH \u00e0 Gen\u00e8ve"},"content":{"rendered":"<p><strong><span class=\"st\">Le Festival du Film et Forum International sur les Droits Humains<\/span> (FIDH) de Gen\u00e8ve pr\u00e9sentera le 14 mars 3 documentaires vid\u00e9o et audio sur les droits Humains au Pakistan, r\u00e9alis\u00e9s dans le cadre d&rsquo;un atelier anim\u00e9 par la Fondation Hirondelle en juillet 2017 \u00e0 Karachi. Ils seront aussi pr\u00e9sent\u00e9s le 15 mars \u00e0 l&rsquo;espace P\u00f4le Sud \u00e0 Lausanne.<br \/><\/strong><\/p>\n<p>\u00ab\u00a0Bahaali\u00a0\u00bb (\u00ab\u00a0Gu\u00e9rison\u00a0\u00bb), un film de 20 mn r\u00e9alis\u00e9 par Tamana Ayazi, Kanzul Fatima Arif et Gulzar Nayani, suit le parcours de deux enfants pakistanais, anciens toxicomanes malgr\u00e9 leur jeune \u00e2ge, qui refusent de laisser leur pass\u00e9 d\u00e9finir leur futur. \u00ab\u00a0Le son du silence\u00a0\u00bb, un film de 20 mn r\u00e9alis\u00e9 par Mohammad Behroozian, Najiba Noori et Nameera Ahmed raconte l&rsquo;histoire de Fariah, 15 ans, sourd de naissance. Son histoire explore les d\u00e9fis de personnes souffrant de handicap \u00e0 Karachi aujourd&rsquo;hui. \u00ab\u00a0Transgenre au Pakistan\u00a0\u00bb, un documentaire audio de 10 mn par Said Nazir Afridi plonge les auditeurs dans la vie quotidienne des transgenres au Pakistan et de leur combat pour trouver du travail.<\/p>\n<p>Ces documentaires ont \u00e9t\u00e9 r\u00e9alis\u00e9s en juillet 2017 par les participants pakistanais et afghans d&rsquo;un atelier de 15 jours co-organis\u00e9 par le Centre d\u2019Information des Nations Unies et l\u2019Ambassade de Suisse au Pakistan, et anim\u00e9 par deux experts de la Fondation Hirondelle. 8 journalistes et r\u00e9alisateurs de documentaires vid\u00e9o et audio, 4 Afghans et 4 Pakistanais, y ont particip\u00e9. Chacun a particip\u00e9 \u00e0 la production d&rsquo;un documentaire pendant la formation, autour de questions li\u00e9es aux droits de l\u2019Homme et \u00e0 la construction de la paix.<\/p>\n<div class=\"itemFullText\">\n<p>Au cours des deux derni\u00e8res ann\u00e9es, le Centre d&rsquo;information des Nations Unies et l&rsquo;Ambassade de Suisse au Pakistan se sont associ\u00e9s pour am\u00e9liorer la diffusion d&rsquo;informations sur les droits de l&rsquo;homme dans tout le pays. Le festival du film \u00ab\u00a0Human Rights through Cinematography\u00a0\u00bb organis\u00e9 en partenariat avec plusieurs Etats membres et le Festival international du film et le Forum des droits de l&rsquo;homme (FIFDH) de Gen\u00e8ve, a offert au public pakistanais l&rsquo;acc\u00e8s \u00e0 de nombreux documentaires professionnels du monde entier sur les droits de l&rsquo;homme. Le festival a amen\u00e9 au Pakistan les principaux experts en production documentaire qui ont interagi avec des publics diversifi\u00e9s. La formation s\u2019inscrivait dans la continuit\u00e9 de cette action.<\/p>\n<p>La projection organis\u00e9e dans le cadre du FIFDH aura lieu le 14 mars \u00e0 18h45 aux Cin\u00e9mas du Gr\u00fctli, salle Henri Langlois, \u00e0 Gen\u00e8ve. Le lendemain la projection aura lieu \u00e0 Lausanne, \u00e0 l&rsquo;espace P\u00f4le Sud, \u00e0 20h. Les documentaires seront diffus\u00e9s en version originale avec sous-titre en anglais. L&rsquo;entr\u00e9e est libre pour ces deux soir\u00e9es.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Festival du Film et Forum International sur les Droits Humains (FIDH) de Gen\u00e8ve pr\u00e9sentera le 14 mars 3 documentaires vid\u00e9o et audio sur les droits Humains au Pakistan, r\u00e9alis\u00e9s dans le cadre d&rsquo;un atelier anim\u00e9 par la Fondation Hirondelle en juillet 2017 \u00e0 Karachi. Ils seront aussi pr\u00e9sent\u00e9s le 15 mars \u00e0 l&rsquo;espace P\u00f4le [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8120,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[171],"tags":[233],"class_list":["post-360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notre-actualite","tag-expertise-construction-de-la-paix"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:58:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=360"}],"version-history":[{"count":0,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/8120"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}