{"id":588,"date":"2019-02-12T18:41:02","date_gmt":"2019-02-12T17:41:02","guid":{"rendered":"https:\/\/www.hirondelle.org\/our-guide-with-the-icrc-to-radio-communication-in-a-humanitarian-context"},"modified":"2019-02-12T18:41:02","modified_gmt":"2019-02-12T17:41:02","slug":"our-guide-with-the-icrc-to-radio-communication-in-a-humanitarian-context","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/our-guide-with-the-icrc-to-radio-communication-in-a-humanitarian-context","title":{"rendered":"Notre guide de communication radio en contexte humanitaire avec le CICR"},"content":{"rendered":"<p><strong>La Fondation Hirondelle et le CICR ont produit un guide sur la communication radio dans les contextes humanitaires. Il est pr\u00e9sent\u00e9 \u00e0 Bamako \u00e0 l&rsquo;occasion de la Journ\u00e9e mondiale de la radio, le 13 f\u00e9vrier.<\/strong><\/p>\n<p>Bien que les tendances actuelles de la communication soient de plus en plus orient\u00e9es vers le num\u00e9rique avec ses possibilit\u00e9s infinies d&rsquo;interaction, la radio reste un moyen de communication majeur. En effet, elle reste le premier m\u00e9dia en audience dans de vastes r\u00e9gions du monde, notamment en Afrique subsaharienne. La technologie radio n&rsquo;exige pas beaucoup d&rsquo;infrastructure, peut \u00eatre re\u00e7ue m\u00eame dans les endroits les plus \u00e9loign\u00e9s et permet une interaction efficace avec les auditeurs. La radio reste aussi consid\u00e9r\u00e9e comme le m\u00e9dia le plus fiable et le plus cr\u00e9dible dans la plupart des sondages d&rsquo;audience.<\/p>\n<p>Du 21 au 23 novembre 2018, huit charg\u00e9s de communication africains francophones du Comit\u00e9 international de la Croix-Rouge (CICR), dont le mandat est d&rsquo;assister les populations touch\u00e9es par les conflits arm\u00e9s, se sont r\u00e9unis \u00e0 Dakar pour partager leurs exp\u00e9riences sur l&rsquo;utilisation de la radio comme outil de communication humanitaire. Avec l&rsquo;aide d&rsquo;Adrien Zerbini, journaliste suisse et formateur de la Fondation Hirondelle, ils ont appris les techniques de base de la production radio et comment \u00e9valuer l&rsquo;impact de leurs campagnes de communication radio.<\/p>\n<p>La Fondation Hirondelle, organisation suisse \u00e0 but non lucratif, fournit de l&rsquo;information \u00e0 des populations confront\u00e9es \u00e0 des crises, pour leur permettre d&rsquo;agir dans leur vie quotidienne et citoyenne. En d\u00e9cembre 2017, le CICR et la Fondation Hirondelle ont sign\u00e9 un accord de partenariat pour promouvoir la collaboration entre leurs \u00e9quipes sur le terrain.<\/p>\n<p>A l&rsquo;issue de cet atelier, le CICR et la Fondation Hirondelle ont produit un guide de communication radio, r\u00e9dig\u00e9 par Adrien Zerbini. L&rsquo;objectif \u00e9tait de consigner par \u00e9crit les bonnes pratiques en mati\u00e8re de radiocommunication et de fournir aux \u00e9quipes du CICR et \u00e0 toutes les organisations humanitaires int\u00e9ress\u00e9es un document simple, facilement utilisable, en deux parties :<\/p>\n<ul>\n<li>Les dix r\u00e8gles d&rsquo;or pour une bonne production radio<\/li>\n<li>Le choix de la bonne production radio et son \u00e9valuation<\/li>\n<\/ul>\n<p>Ce guide a \u00e9t\u00e9 produit en fran\u00e7ais. Il est en cours de traduction par le CICR en anglais, arabe, et espagnol. Le guide est pr\u00e9sent\u00e9 \u00e0 Bamako \u00e0 l&rsquo;occasion de la Journ\u00e9e mondiale de la radio le 13 f\u00e9vrier, dans le cadre d&rsquo;un \u00e9v\u00e9nement organis\u00e9 par Studio Tamani, le programme d&rsquo;information de la Fondation Hirondelle au Mali, avec l&rsquo;URTEL (Union des radios et t\u00e9l\u00e9visions libres du Mali), la Maison de la presse de Bamako, le CICR. Le Ministre malien de la r\u00e9conciliation participera aux discussions, sur le r\u00f4le de la radio comme outil de dialogue et de tol\u00e9rance. Des repr\u00e9sentants de la soci\u00e9t\u00e9 civile malienne, des m\u00e9dias et de la communaut\u00e9 internationale sont attendus parmi les participants.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fondation Hirondelle et le CICR ont produit un guide sur la communication radio dans les contextes humanitaires. Il est pr\u00e9sent\u00e9 \u00e0 Bamako \u00e0 l&rsquo;occasion de la Journ\u00e9e mondiale de la radio, le 13 f\u00e9vrier. Bien que les tendances actuelles de la communication soient de plus en plus orient\u00e9es vers le num\u00e9rique avec ses possibilit\u00e9s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7105,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[171],"tags":[246,261],"class_list":["post-588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notre-actualite","tag-recherche-apprentissage","tag-expertise-crises-humanitaires"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 14:45:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=588"}],"version-history":[{"count":0,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/588\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/7105"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}