{"id":8430,"date":"2017-09-22T13:30:24","date_gmt":"2017-09-22T11:30:24","guid":{"rendered":"https:\/\/www.hirondelle.org\/lutte-contre-les-violences-sexuelles-en-rdc-premier-bilan-de-notre-programme-mon-corps-ma-dignite"},"modified":"2017-09-22T13:30:24","modified_gmt":"2017-09-22T11:30:24","slug":"lutte-contre-les-violences-sexuelles-en-rdc-premier-bilan-de-notre-programme-mon-corps-ma-dignite","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/lutte-contre-les-violences-sexuelles-en-rdc-premier-bilan-de-notre-programme-mon-corps-ma-dignite","title":{"rendered":"Lutte contre les violences sexuelles en RDC : notre programme \u00ab mon corps, ma dignit\u00e9 \u00bb"},"content":{"rendered":"<p><strong>Une \u00e9tude d\u2019audience ind\u00e9pendante permet de tirer un premier bilan de l\u2019impact du programme audiovisuel \u00ab Mon Corps, Ma Dignit\u00e9 \u00bb, lanc\u00e9 en avril 2017 par la Fondation Hirondelle en R\u00e9publique d\u00e9mocratique du Congo (RDC), avec la CTB, agence belge de d\u00e9veloppement. Ce programme traite des violences faites aux jeunes femmes et filles congolaises.<\/strong><\/p>\n<p>La premi\u00e8re campagne du programme \u00ab Mon Corps, Ma Dignit\u00e9 \u00bb a \u00e9t\u00e9 diffus\u00e9e du 29 mai au 9 juillet 2017, par 16 radios communautaires et 7 radios commerciales dans 5 provinces congolaises. Ce programme comprenait la production et diffusion de quatre magazines \u00ab Tous Les Espoirs du Congo \u00bb et d\u2019une s\u00e9rie radiophonique exclusive \u00ab Psy Na Biso \u00bb (\u00ab Notre Psy \u00bb, en Lingala, l\u2019une des principales langues de RDC). Une s\u00e9rie compos\u00e9e de 29 chroniques \u00e0 caract\u00e8re psychologique et de d\u00e9veloppement personnel, prioritairement destin\u00e9es aux femmes et aux jeunes filles, avec le psychologue Jean Lumbala, auteur de \u00ab La vie sexuelle des Congolais \u00bb (L\u2019Harmattan), et le journaliste congolais Patrick Nsimba. 1000 CD reprenant ces productions radiophoniques ont \u00e9galement \u00e9t\u00e9 distribu\u00e9s gratuitement.<\/p>\n<p>L\u2019Institut ind\u00e9pendant IMMAR a r\u00e9alis\u00e9 une \u00e9tude d\u2019impact en juillet 2017 dans les villes de Kinshasa, Mbuji-Mayi et Kisangani apr\u00e8s la diffusion de cette campagne. 537 interviews ont \u00e9t\u00e9 men\u00e9es aupr\u00e8s d\u2019auditrices et auditeurs de moins de 35 ans. La campagne a obtenu d\u2019excellents r\u00e9sultats en termes d\u2019image (+ de 80 % d\u2019avis positifs). Elle a suscit\u00e9 notamment une forte envie de s\u2019informer davantage sur les sujets trait\u00e9s, et une meilleure compr\u00e9hension des comportements \u00e0 adopter au sein des foyers congolais pour diminuer les violences sexuelles. Selon IMMAR \u00ab <em>les personnes sond\u00e9es expriment une \u00e9valuation tout \u00e0 fait remarquable sur l\u2019impact du message v\u00e9hicul\u00e9 puisque tous les scores d\u2019intentions futures abordent un consensus quasi unanime. Par exemple, 97% des r\u00e9pondants d\u00e9clarent que la campagne influence fortement leur engagement dans ce type de pr\u00e9occupations<\/em> \u00bb.<\/p>\n<p>Apr\u00e8s cette premi\u00e8re campagne soutenue par la CTB, la Fondation Hirondelle recherche actuellement de nouveaux partenaires en RDC pour poursuivre le programme \u00ab mon corps, ma dignit\u00e9 \u00bb et augmenter son impact au sein de la soci\u00e9t\u00e9 congolaise.<\/p>\n<p>Les magazines et chroniques de la premi\u00e8re campagne \u00ab\u00a0mon corps, ma dignit\u00e9\u00a0\u00bb peuvent \u00eatre \u00e9cout\u00e9s <a href=\"https:\/\/soundcloud.com\/fondation-hirondelle-rdc\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9tude d\u2019audience ind\u00e9pendante permet de tirer un premier bilan de l\u2019impact du programme audiovisuel \u00ab Mon Corps, Ma Dignit\u00e9 \u00bb, lanc\u00e9 en avril 2017 par la Fondation Hirondelle en R\u00e9publique d\u00e9mocratique du Congo (RDC), avec la CTB, agence belge de d\u00e9veloppement. Ce programme traite des violences faites aux jeunes femmes et filles congolaises. La [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8431,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[171],"tags":[265],"class_list":["post-8430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notre-actualite","tag-operation-en-cours-republique-democratique-du-congo"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:40:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/8430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=8430"}],"version-history":[{"count":0,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/8430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/8431"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=8430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=8430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=8430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}