{"id":8698,"date":"2017-06-15T15:35:17","date_gmt":"2017-06-15T13:35:17","guid":{"rendered":"https:\/\/www.hirondelle.org\/radio-okapi-kindu-l-histoire-vraie-de-l-anti-fake-news-a-l-est-de-la-rdc"},"modified":"2017-06-15T15:35:17","modified_gmt":"2017-06-15T13:35:17","slug":"radio-okapi-kindu-l-histoire-vraie-de-l-anti-fake-news-a-l-est-de-la-rdc","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/radio-okapi-kindu-l-histoire-vraie-de-l-anti-fake-news-a-l-est-de-la-rdc","title":{"rendered":"\u00ab\u00a0Radio Okapi Kindu\u00a0\u00bb : l&rsquo;histoire vraie de \u00ab\u00a0l&rsquo;anti fake news\u00a0\u00bb \u00e0 l&rsquo;Est de la RDC"},"content":{"rendered":"<p>Dans son nouveau livre \u00ab\u00a0Radio Okapi Kindu\u00a0\u00bb, Jennifer Bakody raconte l&rsquo;histoire de son travail avec l&rsquo;\u00e9quipe de Radio Okapi \u00e0 Kindu en 2004, \u00e0 un moment crucial de l&rsquo;histoire congolaise juste avant les premi\u00e8res \u00e9lections d\u00e9mocratiques du pays. L&rsquo;histoire vraie de journalistes d\u00e9di\u00e9s malgr\u00e9 les risques et les difficult\u00e9s \u00e0 l&rsquo;information d&rsquo;une population confront\u00e9e \u00e0 de multiples crises. Notre entretien avec Jennifer Bakody :<\/p>\n<p><strong>Qu&rsquo;est ce qui pousse une jeune journaliste occidentale \u00e0 partir au coeur de la RDC dans une aventure comme celle de Radio Okapi Kindu ?<\/strong><\/p>\n<p>Jennifer Bakody : Avant de partir en RDC, j\u2019avais eu l\u2019opportunit\u00e9 de travailler pour Radio France Internationale et j\u2019avais conscience de la situation du pays et des d\u00e9fis du m\u00e9tier de journaliste en ces temps si particuliers. Je comprenais, sans doute de mani\u00e8re incompl\u00e8te et un peu abstraite encore, l\u2019importance que pouvait avoir l\u2019information de la population dans le processus de paix en cours. J\u2019avais le sentiment de pouvoir contribuer \u00e0 cet \u00e9lan en y apportant mon exp\u00e9rience et ma volont\u00e9.<\/p>\n<p><strong>Cette exp\u00e9rience a-t-elle chang\u00e9 votre vision du journalisme et de son utilit\u00e9 ? Si oui dans quel sens ?<\/strong><\/p>\n<p>JB : Cette exp\u00e9rience a \u00e9t\u00e9 une d\u00e9monstration, \u00e0 une \u00e9chelle peut-\u00eatre unique \u00e0 ce jour, de l\u2019importance du journalisme dans un processus de r\u00e9conciliation et d\u2019unit\u00e9 d\u2019un peuple. Il me semble que la radio plus que tout autre m\u00e9dia a une port\u00e9e universelle qui tient peut-\u00eatre au rapport finalement tr\u00e8s personnel qu\u2019entretiennent les auditeurs avec les voix des journalistes, au d\u00e9but \u00e9trang\u00e8res et puis famili\u00e8res avec le temps qui passe. C\u2019est presqu\u2019un proche qu\u2019on en vient \u00e0 \u00e9couter, un rendez-vous amical o\u00f9 l\u2019auditeur se rend tous les jours.<\/p>\n<p><strong>Vous avez dirig\u00e9 la station de Radio Okapi \u00e0 Kindu, \u00e0 l&rsquo;Est de la RDC, en 2004, alors que le pays se pr\u00e9parait difficilement aux premi\u00e8res \u00e9lections libres de son histoire (qui auront lieu finalement en 2006). Quels exemples concrets et marquants retenez-vous du r\u00f4le de Radio Okapi en RDC et de l&rsquo;utilit\u00e9 de ses informations pour la population ?<\/strong><\/p>\n<p>JB : Je pourrais en \u00e9crire un livre ! Deux exemples puisqu\u2019il faut choisir. Tout d\u2019abord lorsque les repr\u00e9sentants du gouvernement de transition sont venus \u00e0 Kindu, les journalistes de Kindu ont \u00e9videmment couvert l\u2019\u00e9v\u00e9nement et ont interrog\u00e9 le nouveau gouverneur sur ses priorit\u00e9s pour Kindu et sur ce qui concr\u00e8tement allait changer dans les mois \u00e0 venir. <br \/>Je voudrais aussi mentionner la crise de Bukavu : alors que la guerre se rapprochait et que la r\u00e9unification de l\u2019arm\u00e9e semblait compromise, Radio Okapi a inform\u00e9 d\u2019une part Kindu sur ce qui se passait \u00e0 Bukavu et dans le m\u00eame temps les journalistes de Kindu ont inform\u00e9 le pays entier sur les \u00e9v\u00e9nements qui affectaient la r\u00e9gion de Kindu elle-m\u00eame en r\u00e9ponse \u00e0 ces troubles.<\/p>\n<p><strong>Vous d\u00e9crivez tr\u00e8s pr\u00e9cis\u00e9ment dans votre livre le fonctionnement de Radio Okapi \u00e0 cette \u00e9poque, les relations entre journalistes et avec la r\u00e9daction centrale de Kinshasa, les d\u00e9fis de leur travail au quotidien, les relations avec les responsables des Nations Unies sur le terrain&#8230;Qu&rsquo;est-ce qui vous a le plus marqu\u00e9 du fonctionnement de ce m\u00e9dia pas comme les autres ?<\/strong><\/p>\n<p>JB : J\u2019en retiens finalement deux choses principales. D\u2019abord l\u2019impression d\u2019unit\u00e9 et d\u2019harmonie \u00e9ditoriales malgr\u00e9 la distance entre les r\u00e9dactions locales et Kinshasa et la vari\u00e9t\u00e9 des d\u00e9crochages locaux, un peu comme lorsque vous lisez un grand journal, vous avez l\u2019impression que le m\u00eame journaliste a tenu la plume sur toutes les pages. Cela d\u00e9montre l\u2019incroyable effort de professionnalisation qui a \u00e9t\u00e9 accompli en peu de temps. <br \/>Enfin comment ne pas mentionner le s\u00e9rieux et l\u2019ing\u00e9niosit\u00e9 des journalistes d\u2019Okapi pour d\u00e9nicher et raconter les sujets qui ont fait adh\u00e9rer la population au projet Okapi?<\/p>\n<p><strong>Qu&rsquo;est ce qui selon vous, dans cette aventure collective congolaise que vous avez v\u00e9cue, peut faire \u00e9cho aujourd&rsquo;hui pour les audiences occidentales, notamment anglo-saxonnes qui vont lire votre livre ?<\/strong><\/p>\n<p>JB : Radio Okapi, c\u2019est \u00ab l\u2019anti fake news \u00bb ou comment le journalisme, professionnel et dot\u00e9 de moyens fait progresser la soci\u00e9t\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans son nouveau livre \u00ab\u00a0Radio Okapi Kindu\u00a0\u00bb, Jennifer Bakody raconte l&rsquo;histoire de son travail avec l&rsquo;\u00e9quipe de Radio Okapi \u00e0 Kindu en 2004, \u00e0 un moment crucial de l&rsquo;histoire congolaise juste avant les premi\u00e8res \u00e9lections d\u00e9mocratiques du pays. L&rsquo;histoire vraie de journalistes d\u00e9di\u00e9s malgr\u00e9 les risques et les difficult\u00e9s \u00e0 l&rsquo;information d&rsquo;une population confront\u00e9e \u00e0 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8699,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[173],"tags":[233,246,275],"class_list":["post-8698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","tag-expertise-construction-de-la-paix","tag-recherche-apprentissage","tag-ancien-projet-republique-democratique-du-congo"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:59:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/8698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=8698"}],"version-history":[{"count":0,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/8698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/8699"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=8698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=8698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=8698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}