{"id":977,"date":"2019-10-17T08:21:08","date_gmt":"2019-10-17T06:21:08","guid":{"rendered":"https:\/\/www.hirondelle.org\/discussion-autour-de-la-place-des-femmes-en-politique-en-rdc"},"modified":"2019-10-17T08:21:08","modified_gmt":"2019-10-17T06:21:08","slug":"discussion-autour-de-la-place-des-femmes-en-politique-en-rdc","status":"publish","type":"post","link":"https:\/\/www.hirondelle.org\/fr\/discussion-autour-de-la-place-des-femmes-en-politique-en-rdc","title":{"rendered":"Discussion autour de la place des femmes en politique en RDC"},"content":{"rendered":"<p><strong>Un d\u00e9bat, organis\u00e9 par Studio Hirondelle RDC le 30 septembre dernier, a soulev\u00e9 de nombreuses questions autour de la place des femmes en politique.<\/strong><\/p>\n<p>La discussion avait pour th\u00e8me \u00ab\u00a0femmes et \u00e9lections: je suis candidate, je veux g\u00e9rer ma communaut\u00e9\u00a0\u00bb et s&rsquo;est tenu le 30 septembre dernier \u00e0 Kindu, dans l&rsquo;est du pays. Trois invit\u00e9s ont anim\u00e9 ce d\u00e9bat dont; Getrude Kitembo, la pr\u00e9sidente de l&rsquo;assembl\u00e9e provinciale du Maniema, Jacques Misako, sp\u00e9cialiste en gouvernance locale, et Keren Laini, coordinatrice de l&rsquo;association des femmes juristes du Congo.<\/p>\n<p>Les trois experts ont r\u00e9pondu aux questions du public, venu nombreux pour assister \u00e0 l&rsquo;\u00e9mission retransmise en direct. Plus de 400 femmes et hommes (presque \u00e0 parit\u00e9) ont particip\u00e9 \u00e0 cet \u00e9change dont l&rsquo;objectif \u00e9tait de faire \u00e9voluer la perception des femmes engag\u00e9es pour leur communaut\u00e9, et de susciter des vocations en politique aupr\u00e8s des femmes.<\/p>\n<p>L&rsquo;\u00e9mission est disponible int\u00e9gralement <a href=\"https:\/\/www.studiohirondellerdc.org\/productions\/hirondelle-debats\/302-un-hirondelle-debat-sur-la-participation-de-femmes-aux-elections-locales-a-mbandaka-dans-la-province-de-l-equateur.html\" target=\"_blank\" rel=\"noopener\">ici<\/a><\/p>\n<div id=\"simple-translate\">\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00e9bat, organis\u00e9 par Studio Hirondelle RDC le 30 septembre dernier, a soulev\u00e9 de nombreuses questions autour de la place des femmes en politique. La discussion avait pour th\u00e8me \u00ab\u00a0femmes et \u00e9lections: je suis candidate, je veux g\u00e9rer ma communaut\u00e9\u00a0\u00bb et s&rsquo;est tenu le 30 septembre dernier \u00e0 Kindu, dans l&rsquo;est du pays. Trois invit\u00e9s [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":6214,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[172],"tags":[265,384],"class_list":["post-977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nos-medias","tag-operation-en-cours-republique-democratique-du-congo","tag-expertise-gouvernance-et-processus-democratique"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:59:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/comments?post=977"}],"version-history":[{"count":0,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/posts\/977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media\/6214"}],"wp:attachment":[{"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/media?parent=977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/categories?post=977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hirondelle.org\/fr\/wp-json\/wp\/v2\/tags?post=977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}